{"id":46196,"date":"2024-11-01T09:52:38","date_gmt":"2024-11-01T14:52:38","guid":{"rendered":"https:\/\/www.uniagraria.edu.co\/?p=46196"},"modified":"2024-11-01T09:52:38","modified_gmt":"2024-11-01T14:52:38","slug":"actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua","status":"publish","type":"post","link":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/","title":{"rendered":"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua"},"content":{"rendered":"<h4 class=\"wp-block-heading\" id=\"mce_0\"><strong>Direcci\u00f3n de Comunicaciones UNIAGRARIA<\/strong><\/h4>\n\n\n\n<p style=\"text-align: justify;\">Ingenier\u00eda de Alimentos para la Sociedad. El d\u00eda 21 de octubre de 2024, la comunidad acad\u00e9mica del Programa de Ingenier\u00eda de Alimentos particip\u00f3 en el Primer Encuentro para el Intercambio de Saberes en el Colegio Campestre de Cogua, un evento dise\u00f1ado por el Programa de Ingenier\u00eda de Alimentos en el marco de la estrategia de regionalizaci\u00f3n de UNIAGRARIA: Plan 500 y el convenio vigente entre ambas instituciones de educaci\u00f3n, donde se articula el curr\u00edculo, las estrategias de regionalizaci\u00f3n, y actividades de extensi\u00f3n.<\/p>\n\n\n\n<p style=\"text-align: justify;\">47 estudiantes de las asignaturas de Termodin\u00e1mica, Manejo poscosecha, microbiolog\u00eda para ingenieros, legislaci\u00f3n internacional y qu\u00edmica de alimentos; bajo la orientaci\u00f3n de los docentes \u00c1ngela Far\u00edas, Camila Bernal y Mauricio Buitrago realizaron una jornada acad\u00e9mica cuyo prop\u00f3sito fue contribuir al desarrollo regional y local a partir de la construcci\u00f3n de saberes en conjunto con estudiantes de colegios rurales.<\/p>\n\n\n\n<p style=\"text-align: justify;\">La jornada inici\u00f3 con la charla titulada \u201cSuperalimentos: Nutrici\u00f3n Inteligente para el Bienestar de Toda la Familia\u201d dirigida a padres de familia, profesores y estudiantes del colegio, siendo una oportunidad para comunicar sobre la importancia de la nutrici\u00f3n en la salud integral de la comunidad educativa desmintiendo mitos y presentando los \u00faltimos hallazgos de la nutrici\u00f3n humana.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Posteriormente, 150 estudiantes de grado jard\u00edn hasta und\u00e9cimo del Colegio Campestre de Cogua participaron en actividades l\u00fadicas como juegos de rol y exposiciones tem\u00e1ticas enfocadas al desarrollo de competencias en ciencias naturales. Entre las actividades desarrolladas se destacan talleres de creaci\u00f3n, talleres te\u00f3rico- pr\u00e1ctico de qu\u00edmica, f\u00edsica, microbiolog\u00eda y matem\u00e1tica, taller de habilidades blandas, concurso de innovaci\u00f3n y exposici\u00f3n de arte para los m\u00e1s peque\u00f1os.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Con el fin de fortalecer la integraci\u00f3n de ambas instituciones y el esp\u00edritu deportivo, la jornada finaliz\u00f3 con un torneo de futbol y voleibol entre los estudiantes de UNIAGRARIA y los j\u00f3venes del colegio Campestre de Cogua. El programa de Ingenier\u00eda de Alimentos agradece a los estudiantes, docentes y directivos del colegio por la oportunidad de impactar a la comunidad educativa en el marco de la estrategia de Plan 500 de UNIAGRARIA.<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2024\/11\/ActividadesDePlan500EnCogua-01-1024x576.jpeg\" alt=\"\" data-id=\"46190\" data-link=\"https:\/\/www.uniagraria.edu.co\/actividadesdeplan500encogua-01\/\" class=\"wp-image-46190\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2024\/11\/ActividadesDePlan500EnCogua-04-1024x768.jpeg\" alt=\"\" data-id=\"46193\" data-link=\"https:\/\/www.uniagraria.edu.co\/actividadesdeplan500encogua-04\/\" class=\"wp-image-46193\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2024\/11\/ActividadesDePlan500EnCogua-03-1024x768.jpeg\" alt=\"\" data-id=\"46192\" data-link=\"https:\/\/www.uniagraria.edu.co\/actividadesdeplan500encogua-03\/\" class=\"wp-image-46192\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2024\/11\/ActividadesDePlan500EnCogua-05-1024x768.jpeg\" alt=\"\" data-id=\"46194\" data-link=\"https:\/\/www.uniagraria.edu.co\/actividadesdeplan500encogua-05\/\" class=\"wp-image-46194\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2024\/11\/ActividadesDePlan500EnCogua-02-1024x768.jpeg\" alt=\"\" data-id=\"46191\" data-link=\"https:\/\/www.uniagraria.edu.co\/actividadesdeplan500encogua-02\/\" class=\"wp-image-46191\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2024\/11\/ActividadesDePlan500EnCogua-06-1024x770.jpeg\" alt=\"\" data-id=\"46195\" data-link=\"https:\/\/www.uniagraria.edu.co\/actividadesdeplan500encogua-06\/\" class=\"wp-image-46195\"\/><\/figure><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n de Comunicaciones UNIAGRARIA Ingenier\u00eda de Alimentos para la Sociedad. El d\u00eda 21 de octubre de 2024, la comunidad acad\u00e9mica del Programa de Ingenier\u00eda de Alimentos particip\u00f3 en el Primer Encuentro para el Intercambio de Saberes en el Colegio Campestre de Cogua, un evento dise\u00f1ado por el Programa de Ingenier\u00eda de Alimentos en el marco [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":46190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[35],"tags":[],"class_list":["post-46196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua - UNIAGRARIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua - UNIAGRARIA\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n de Comunicaciones UNIAGRARIA Ingenier\u00eda de Alimentos para la Sociedad. El d\u00eda 21 de octubre de 2024, la comunidad acad\u00e9mica del Programa de Ingenier\u00eda de Alimentos particip\u00f3 en el Primer Encuentro para el Intercambio de Saberes en el Colegio Campestre de Cogua, un evento dise\u00f1ado por el Programa de Ingenier\u00eda de Alimentos en el marco [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIAGRARIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-01T14:52:38+00:00\" \/>\n<meta name=\"author\" content=\"Comunicaciones UNIAGRARIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:site\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones UNIAGRARIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/\"},\"author\":{\"name\":\"Comunicaciones UNIAGRARIA\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/0e33f5fa0e8c069958129cbe1ddd943f\"},\"headline\":\"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua\",\"datePublished\":\"2024-11-01T14:52:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/\"},\"wordCount\":401,\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/\",\"name\":\"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua - UNIAGRARIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2024-11-01T14:52:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"name\":\"UNIAGRARIA\",\"description\":\"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\",\"name\":\"UNIAGRARIA\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"contentUrl\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"width\":3300,\"height\":2550,\"caption\":\"UNIAGRARIA\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uagraria\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/UNIAGRARIA\",\"https:\\\/\\\/www.instagram.com\\\/uniagraria\\\/profilecard\\\/?igsh=MXI2bTFlMWsxNzNjOA\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/uniagraria?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/uniagraria\\\/?originalSubdomain=co\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UniagrariaUverde?themeRefresh=1\",\"https:\\\/\\\/api.whatsapp.com\\\/send?phone=3134230649\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/0e33f5fa0e8c069958129cbe1ddd943f\",\"name\":\"Comunicaciones UNIAGRARIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones UNIAGRARIA\"},\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/author\\\/daniel-castellanos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua - UNIAGRARIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/","og_locale":"en_US","og_type":"article","og_title":"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua - UNIAGRARIA","og_description":"Direcci\u00f3n de Comunicaciones UNIAGRARIA Ingenier\u00eda de Alimentos para la Sociedad. El d\u00eda 21 de octubre de 2024, la comunidad acad\u00e9mica del Programa de Ingenier\u00eda de Alimentos particip\u00f3 en el Primer Encuentro para el Intercambio de Saberes en el Colegio Campestre de Cogua, un evento dise\u00f1ado por el Programa de Ingenier\u00eda de Alimentos en el marco [&hellip;]","og_url":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/","og_site_name":"UNIAGRARIA","article_publisher":"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","article_published_time":"2024-11-01T14:52:38+00:00","author":"Comunicaciones UNIAGRARIA","twitter_card":"summary_large_image","twitter_creator":"@UNIAGRARIA","twitter_site":"@UNIAGRARIA","twitter_misc":{"Written by":"Comunicaciones UNIAGRARIA","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/#article","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/"},"author":{"name":"Comunicaciones UNIAGRARIA","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/0e33f5fa0e8c069958129cbe1ddd943f"},"headline":"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua","datePublished":"2024-11-01T14:52:38+00:00","mainEntityOfPage":{"@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/"},"wordCount":401,"publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"image":{"@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/","url":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/","name":"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua - UNIAGRARIA","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/#primaryimage"},"image":{"@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/#primaryimage"},"thumbnailUrl":"","datePublished":"2024-11-01T14:52:38+00:00","breadcrumb":{"@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/uniagraria.edu.co\/en\/actividades-de-plan-500-en-cogua-programa-de-ingenieria-de-alimentos-participa-en-el-encuentro-para-el-intercambio-de-saberes-en-el-colegio-campestre-de-cogua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/uniagraria.edu.co\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/uniagraria.edu.co\/es\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Actividades de Plan 500 en Cogua. Programa de Ingenier\u00eda de Alimentos participa en el Encuentro para el intercambio de saberes en el Colegio Campestre de Cogua"}]},{"@type":"WebSite","@id":"https:\/\/uniagraria.edu.co\/es\/#website","url":"https:\/\/uniagraria.edu.co\/es\/","name":"Experience the experience and discover the education of","description":"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA","publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniagraria.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uniagraria.edu.co\/es\/#organization","name":"Experience the experience and discover the education of","url":"https:\/\/uniagraria.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","contentUrl":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","width":3300,"height":2550,"caption":"UNIAGRARIA"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","https:\/\/x.com\/UNIAGRARIA","https:\/\/www.instagram.com\/uniagraria\/profilecard\/?igsh=MXI2bTFlMWsxNzNjOA","https:\/\/www.tiktok.com\/discover\/uniagraria?lang=es","https:\/\/www.linkedin.com\/school\/uniagraria\/?originalSubdomain=co","https:\/\/www.youtube.com\/user\/UniagrariaUverde?themeRefresh=1","https:\/\/api.whatsapp.com\/send?phone=3134230649"]},{"@type":"Person","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/0e33f5fa0e8c069958129cbe1ddd943f","name":"Communications UNIAGRARIA","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","caption":"Comunicaciones UNIAGRARIA"},"url":"https:\/\/uniagraria.edu.co\/en\/author\/daniel-castellanos\/"}]}},"_links":{"self":[{"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/posts\/46196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/comments?post=46196"}],"version-history":[{"count":0,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/posts\/46196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/media?parent=46196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/categories?post=46196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/tags?post=46196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}