{"id":77486,"date":"2025-09-16T12:31:45","date_gmt":"2025-09-16T17:31:45","guid":{"rendered":"https:\/\/novawebmaster.com\/uniagraria\/?p=77486"},"modified":"2026-02-11T12:15:36","modified_gmt":"2026-02-11T17:15:36","slug":"uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de","status":"publish","type":"post","link":"https:\/\/uniagraria.edu.co\/en\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/","title":{"rendered":"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"77486\" class=\"elementor elementor-77486\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-420ce0b1 e-flex e-con-boxed e-con e-parent\" data-id=\"420ce0b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e084f57 elementor-widget elementor-widget-text-editor\" data-id=\"7e084f57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"uk-container uk-container-xsmall\">UNIAGRARIA particip\u00f3 activamente en el GoFest 2025, el festival de emprendimiento e innovaci\u00f3n m\u00e1s grande de Colombia, organizado por la C\u00e1mara de Comercio de Bogot\u00e1. Este importante evento tuvo como prop\u00f3sito fortalecer el ecosistema emprendedor del pa\u00eds, conectando a j\u00f3venes, emprendedores, empresas e instituciones acad\u00e9micas en un mismo espacio de creaci\u00f3n y colaboraci\u00f3n.<\/p>\r\n<p class=\"uk-container uk-container-xsmall\">Dentro de la agenda del festival, nuestra instituci\u00f3n se destac\u00f3 en el 3DE (Tres D\u00edas de Emprendimiento), un espacio intensivo de aprendizaje realizado entre el 27 y el 29 de agosto de 2025, dise\u00f1ado para impulsar el emprendimiento en los j\u00f3venes universitarios a trav\u00e9s de la resoluci\u00f3n de retos de innovaci\u00f3n reales planteados por empresas l\u00edderes.<\/p>\r\n\r\n<h3 class=\"uk-container uk-container-xsmall\"><strong>Din\u00e1mica y retos del 3DE 2025<\/strong><\/h3>\r\n<p class=\"uk-container uk-container-xsmall\">El 3DE 2025 fue organizado por la C\u00e1mara de Comercio de Bogot\u00e1 junto a las universidades participantes, entre ellas UNIAGRARIA. Durante tres d\u00edas, los estudiantes trabajaron en equipos multidisciplinarios, recibieron mentor\u00eda especializada y formaci\u00f3n en metodolog\u00edas de innovaci\u00f3n, y enfrentaron los desaf\u00edos propuestos por Comestibles Ricos, Schneider Electric y la Corporaci\u00f3n Colombiana de Log\u00edstica (CCL).<\/p>\r\n<p class=\"uk-container uk-container-xsmall\">Los retos se centraron en el desarrollo de nuevos productos, la optimizaci\u00f3n de procesos y la creaci\u00f3n de soluciones sostenibles, fomentando en los estudiantes habilidades como liderazgo, trabajo en equipo, pensamiento cr\u00edtico, resoluci\u00f3n de problemas, creatividad e innovaci\u00f3n.<\/p>\r\n\r\n<h3 class=\"uk-container uk-container-xsmall\"><strong>Reconocimiento a los estudiantes ganadores de UNIAGRARIA<\/strong><\/h3>\r\n<p class=\"uk-container uk-container-xsmall\">El talento y compromiso de nuestros estudiantes se reflej\u00f3 en los excelentes resultados obtenidos en esta edici\u00f3n del 3DE, dejando en alto el nombre de la instituci\u00f3n y demostrando el impacto de la formaci\u00f3n acad\u00e9mica que reciben en el fortalecimiento del esp\u00edritu emprendedor.<\/p>\r\n<p class=\"uk-container uk-container-xsmall\">Los siguientes estudiantes de UNIAGRARIA fueron reconocidos en el 3DE 2025:<\/p>\r\n\r\n<ul class=\"uk-container uk-container-xsmall\">\r\n \t<li>Ferney Santiago Villamil Salinas: Primer puesto con el reto de CCL.<\/li>\r\n \t<li>Juan Manuel G\u00f3mez Garc\u00eda: Primer puesto con el reto de Comestibles Ricos.<\/li>\r\n \t<li>Kevin Juli\u00e1n Reyes Duque: Segundo puesto con el reto de Schneider Electric (Dexson).<\/li>\r\n \t<li>Jos\u00e9 Santiago Caro Galvis: Segundo puesto con el reto de Comestibles Ricos.<\/li>\r\n \t<li>Edgar Dami\u00e1n T\u00e9llez Conde: Tercer puesto con el reto de Comestibles Ricos.<\/li>\r\n<\/ul>\r\n<p class=\"uk-container uk-container-xsmall\">Estos logros son motivo de orgullo para toda la comunidad UNIAGRARIA y ratifican el potencial de nuestros estudiantes para convertirse en los futuros l\u00edderes, emprendedores e innovadores de Colombia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57a11a4 e-flex e-con-boxed e-con e-parent\" data-id=\"57a11a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f35f113 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"f35f113\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-e2b74c8 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"UniagrariaBrilloEnElGoFest2025-01\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-c6897bf swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"UniagrariaBrilloEnElGoFest2025-02\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-39bb77c swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"UniagrariaBrilloEnElGoFest2025-03\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-0ab1337 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"UniagrariaBrilloEnElGoFest2025-04\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-8a04123 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"UniagrariaBrilloEnElGoFest2025-05\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-53151e3 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"UniagrariaBrilloEnElGoFest2025-07\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>UNIAGRARIA particip\u00f3 activamente en el GoFest 2025, el festival de emprendimiento e innovaci\u00f3n m\u00e1s grande de Colombia, organizado por la C\u00e1mara de Comercio de Bogot\u00e1. Este importante evento tuvo como prop\u00f3sito fortalecer el ecosistema emprendedor del pa\u00eds, conectando a j\u00f3venes, emprendedores, empresas e instituciones acad\u00e9micas en un mismo espacio de creaci\u00f3n y colaboraci\u00f3n. Dentro de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":77485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9,35,92],"tags":[],"class_list":["post-77486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-noticias","category-novedades-de-emprendimiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE - UNIAGRARIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniagraria.edu.co\/en\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE - UNIAGRARIA\" \/>\n<meta property=\"og:description\" content=\"UNIAGRARIA particip\u00f3 activamente en el GoFest 2025, el festival de emprendimiento e innovaci\u00f3n m\u00e1s grande de Colombia, organizado por la C\u00e1mara de Comercio de Bogot\u00e1. Este importante evento tuvo como prop\u00f3sito fortalecer el ecosistema emprendedor del pa\u00eds, conectando a j\u00f3venes, emprendedores, empresas e instituciones acad\u00e9micas en un mismo espacio de creaci\u00f3n y colaboraci\u00f3n. Dentro de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniagraria.edu.co\/en\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIAGRARIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T17:31:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T17:15:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/09\/UniagrariaBrilloEnElGoFest2025-01.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones UNIAGRARIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:site\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones UNIAGRARIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/\"},\"author\":{\"name\":\"Comunicaciones UNIAGRARIA\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/0e33f5fa0e8c069958129cbe1ddd943f\"},\"headline\":\"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE\",\"datePublished\":\"2025-09-16T17:31:45+00:00\",\"dateModified\":\"2026-02-11T17:15:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/\"},\"wordCount\":406,\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/UniagrariaBrilloEnElGoFest2025-01.jpeg\",\"articleSection\":[\"Noticia\",\"Noticias\",\"Novedades de emprendimiento\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/\",\"name\":\"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE - UNIAGRARIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/UniagrariaBrilloEnElGoFest2025-01.jpeg\",\"datePublished\":\"2025-09-16T17:31:45+00:00\",\"dateModified\":\"2026-02-11T17:15:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/UniagrariaBrilloEnElGoFest2025-01.jpeg\",\"contentUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/UniagrariaBrilloEnElGoFest2025-01.jpeg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/category\\\/noticia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"name\":\"UNIAGRARIA\",\"description\":\"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\",\"name\":\"UNIAGRARIA\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"contentUrl\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"width\":3300,\"height\":2550,\"caption\":\"UNIAGRARIA\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uagraria\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/UNIAGRARIA\",\"https:\\\/\\\/www.instagram.com\\\/uniagraria\\\/profilecard\\\/?igsh=MXI2bTFlMWsxNzNjOA\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/uniagraria?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/uniagraria\\\/?originalSubdomain=co\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UniagrariaUverde?themeRefresh=1\",\"https:\\\/\\\/api.whatsapp.com\\\/send?phone=3134230649\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/0e33f5fa0e8c069958129cbe1ddd943f\",\"name\":\"Comunicaciones UNIAGRARIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones UNIAGRARIA\"},\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/author\\\/daniel-castellanos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE - UNIAGRARIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniagraria.edu.co\/en\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/","og_locale":"en_US","og_type":"article","og_title":"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE - UNIAGRARIA","og_description":"UNIAGRARIA particip\u00f3 activamente en el GoFest 2025, el festival de emprendimiento e innovaci\u00f3n m\u00e1s grande de Colombia, organizado por la C\u00e1mara de Comercio de Bogot\u00e1. Este importante evento tuvo como prop\u00f3sito fortalecer el ecosistema emprendedor del pa\u00eds, conectando a j\u00f3venes, emprendedores, empresas e instituciones acad\u00e9micas en un mismo espacio de creaci\u00f3n y colaboraci\u00f3n. Dentro de [&hellip;]","og_url":"https:\/\/uniagraria.edu.co\/en\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/","og_site_name":"UNIAGRARIA","article_publisher":"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","article_published_time":"2025-09-16T17:31:45+00:00","article_modified_time":"2026-02-11T17:15:36+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/09\/UniagrariaBrilloEnElGoFest2025-01.jpeg","type":"image\/jpeg"}],"author":"Comunicaciones UNIAGRARIA","twitter_card":"summary_large_image","twitter_creator":"@UNIAGRARIA","twitter_site":"@UNIAGRARIA","twitter_misc":{"Written by":"Comunicaciones UNIAGRARIA","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/#article","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/"},"author":{"name":"Comunicaciones UNIAGRARIA","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/0e33f5fa0e8c069958129cbe1ddd943f"},"headline":"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE","datePublished":"2025-09-16T17:31:45+00:00","dateModified":"2026-02-11T17:15:36+00:00","mainEntityOfPage":{"@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/"},"wordCount":406,"publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"image":{"@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/#primaryimage"},"thumbnailUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/09\/UniagrariaBrilloEnElGoFest2025-01.jpeg","articleSection":["Noticia","Noticias","Novedades de emprendimiento"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/","url":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/","name":"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE - UNIAGRARIA","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/#primaryimage"},"image":{"@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/#primaryimage"},"thumbnailUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/09\/UniagrariaBrilloEnElGoFest2025-01.jpeg","datePublished":"2025-09-16T17:31:45+00:00","dateModified":"2026-02-11T17:15:36+00:00","breadcrumb":{"@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/#primaryimage","url":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/09\/UniagrariaBrilloEnElGoFest2025-01.jpeg","contentUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/09\/UniagrariaBrilloEnElGoFest2025-01.jpeg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/uniagraria.edu.co\/uniagraria-brillo-en-el-gofest-2025-con-destacados-resultados-en-el-3de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/uniagraria.edu.co\/"},{"@type":"ListItem","position":2,"name":"Noticia","item":"https:\/\/uniagraria.edu.co\/es\/category\/noticia\/"},{"@type":"ListItem","position":3,"name":"UNIAGRARIA brill\u00f3 en el GoFest 2025 con destacados resultados en el 3DE"}]},{"@type":"WebSite","@id":"https:\/\/uniagraria.edu.co\/es\/#website","url":"https:\/\/uniagraria.edu.co\/es\/","name":"Experience the experience and discover the education of","description":"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA","publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniagraria.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uniagraria.edu.co\/es\/#organization","name":"Experience the experience and discover the education of","url":"https:\/\/uniagraria.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","contentUrl":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","width":3300,"height":2550,"caption":"UNIAGRARIA"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","https:\/\/x.com\/UNIAGRARIA","https:\/\/www.instagram.com\/uniagraria\/profilecard\/?igsh=MXI2bTFlMWsxNzNjOA","https:\/\/www.tiktok.com\/discover\/uniagraria?lang=es","https:\/\/www.linkedin.com\/school\/uniagraria\/?originalSubdomain=co","https:\/\/www.youtube.com\/user\/UniagrariaUverde?themeRefresh=1","https:\/\/api.whatsapp.com\/send?phone=3134230649"]},{"@type":"Person","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/0e33f5fa0e8c069958129cbe1ddd943f","name":"Communications UNIAGRARIA","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","caption":"Comunicaciones UNIAGRARIA"},"url":"https:\/\/uniagraria.edu.co\/en\/author\/daniel-castellanos\/"}]}},"_links":{"self":[{"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/posts\/77486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/comments?post=77486"}],"version-history":[{"count":0,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/posts\/77486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/media\/77485"}],"wp:attachment":[{"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/media?parent=77486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/categories?post=77486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/en\/wp-json\/wp\/v2\/tags?post=77486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}