{"id":57630,"date":"2025-02-27T21:09:03","date_gmt":"2025-02-28T02:09:03","guid":{"rendered":"https:\/\/novawebmaster.com\/uniagraria\/?page_id=57630"},"modified":"2025-11-27T11:19:38","modified_gmt":"2025-11-27T16:19:38","slug":"valor-matriculas","status":"publish","type":"page","link":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/","title":{"rendered":"Valor Matr\u00edculas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"57630\" class=\"elementor elementor-57630\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1086338 e-flex e-con-boxed e-con e-parent\" data-id=\"1086338\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ceea205 e-con-full e-flex e-con e-child\" data-id=\"ceea205\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4339bcc e-con-full e-flex e-con e-child\" data-id=\"4339bcc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b885bf e-con-full e-flex e-con e-child\" data-id=\"7b885bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e099ff9 elementor-widget elementor-widget-heading\" data-id=\"e099ff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a0Valor de las Matr\u00edculas\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23e393e elementor-widget elementor-widget-text-editor\" data-id=\"23e393e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Estudia a un costo Accesible<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57f24b8 e-flex e-con-boxed e-con e-parent\" data-id=\"57f24b8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-483408d e-con-full e-flex e-con e-child\" data-id=\"483408d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-37bbe27 e-con-full e-flex e-con e-child\" data-id=\"37bbe27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ac68c0 elementor-widget elementor-widget-button\" data-id=\"8ac68c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/11\/AcuerdoNo1198DerechosPecuniarios2026-02.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-down\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm-32-316v116h-67c-10.7 0-16 12.9-8.5 20.5l99 99c4.7 4.7 12.3 4.7 17 0l99-99c7.6-7.6 2.2-20.5-8.5-20.5h-67V140c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Acuerdo No. 1198 del 12 de noviembre de 2025 - por el cual se establecen los valores de matr\u00edcula y otros derechos pecuniarios para los estudiantes de UNIAGRARIA para el a\u00f1o 2026<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ecb70e e-con-full e-flex e-con e-child\" data-id=\"9ecb70e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7766b26 elementor-widget elementor-widget-image\" data-id=\"7766b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/elementor\/thumbs\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png\" title=\"2\" alt=\"2\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16ceafe e-flex e-con-boxed e-con e-parent\" data-id=\"16ceafe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70ee582 e-con-full e-flex e-con e-child\" data-id=\"70ee582\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ef7c24c e-con-full e-flex e-con e-child\" data-id=\"ef7c24c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-beac0e4 elementor-widget elementor-widget-heading\" data-id=\"beac0e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pregrado<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-105d288 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"105d288\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a87e026 e-con-full e-flex e-con e-child\" data-id=\"a87e026\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5a4896a e-con-full e-flex e-con e-child\" data-id=\"5a4896a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb9564 elementor-widget elementor-widget-text-editor\" data-id=\"3eb9564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Programas de pregrado, por ciclo acad\u00e9mico, para los estudiantes de <strong>PRIMERA MATR\u00cdCULA<\/strong> en el a\u00f1o 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a662e3 elementor-widget elementor-widget-text-editor\" data-id=\"6a662e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 0%; height: 19px;\"><span style=\"font-size: 12pt;\">Administraci\u00f3n de Empresas<\/span><\/td><td style=\"width: 34.2912%; height: 19px;\">$2.954.000<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Contadur\u00eda P\u00fablica<\/td><td style=\"width: 34.2912%; height: 53px;\">$4.905.500<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Derecho<\/td><td style=\"width: 34.2912%; height: 53px;\">$6.273.000<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Agroindustrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Ambiental<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Civil<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Alimentos<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Industrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.123.550<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Mecatr\u00f3nica<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Medicina Veterinaria<\/td><td style=\"width: 34.2912%; height: 53px;\">$9.636.100<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Zootecnia<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.959.000<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4303b7f e-con-full e-flex e-con e-child\" data-id=\"4303b7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab6623e elementor-widget elementor-widget-text-editor\" data-id=\"ab6623e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0Programas de pregrado, por ciclo acad\u00e9mico, para estudiantes <strong>antiguos que mantenga continuidad.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f4a4db elementor-widget elementor-widget-text-editor\" data-id=\"0f4a4db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 0%; height: 19px;\"><span style=\"font-size: 12pt;\">Administraci\u00f3n de Empresas<\/span><\/td><td style=\"width: 34.2912%; height: 19px;\">$2.954.000<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Administraci\u00f3n financiera y de Sistemas<\/td><td style=\"width: 34.2912%; height: 53px;\">$5.186.100<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Contadur\u00eda P\u00fablica<\/td><td style=\"width: 34.2912%; height: 53px;\">$4.905.500<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Derecho<\/td><td style=\"width: 34.2912%; height: 53px;\">$6.273.000<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Agroindustrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Ambiental<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Civil<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Alimentos<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Industrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.123.550<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Mecatr\u00f3nica<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.226.300<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Medicina Veterinaria<\/td><td style=\"width: 34.2912%; height: 53px;\">$9.636.100<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Zootecnia<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.959.000<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-903dbae e-flex e-con-boxed e-con e-parent\" data-id=\"903dbae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0dace7b e-con-full e-flex e-con e-child\" data-id=\"0dace7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-edbe698 e-con-full e-flex e-con e-child\" data-id=\"edbe698\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e0a91e elementor-widget elementor-widget-heading\" data-id=\"3e0a91e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Posgrados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a387ab9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a387ab9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20357a3 e-con-full e-flex e-con e-child\" data-id=\"20357a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7c3149f e-con-full e-flex e-con e-child\" data-id=\"7c3149f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-395b443 elementor-widget elementor-widget-text-editor\" data-id=\"395b443\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Programas de posgrado, por ciclo acad\u00e9mico, para los estudiantes de <strong>PRIMERA MATR\u00cdCULA<\/strong> en el a\u00f1o 2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-346f07c elementor-widget elementor-widget-text-editor\" data-id=\"346f07c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 0%; height: 19px;\">Especializaci\u00f3n en Bienestar Animal y Etolog\u00eda (Virtual)<\/td><td style=\"width: 34.2912%; height: 19px;\">$7.625.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Derecho Procesal<\/td><td style=\"width: 34.2912%; height: 53px;\">$8.983.350<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Educaci\u00f3n en Contextos Rurales (Virtual)<\/td><td style=\"width: 34.2912%; height: 53px;\">$3.848.500<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Gesti\u00f3n de Agronegocios (Virtual)<\/td><td style=\"width: 34.2912%; height: 53px;\">$4.447.800<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Legislaci\u00f3n Rural y Ordenamiento Territorial (Registro \u00danico)<\/td><td style=\"width: 34.2912%; height: 53px;\">$8.983.350<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Responsabilidad Ambiental y Sostenibilidad (Presencial)<\/td><td style=\"width: 34.2912%; height: 53px;\">$8.472.550<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Salud Publica Veterinaria (Virtual)<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.625.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Seguridad Industrial, Higiene y Gesti\u00f3n Ambiental (Presencial)<\/td><td style=\"width: 34.2912%; height: 53px;\">$6.466.900<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Sistemas de Gesti\u00f3n Integrada de la Calidad, Medio Ambiente y Prevenci\u00f3n de Riesgos Laborales (Presencial)<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.950.100<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Maestr\u00eda en Ingenier\u00eda (Presencial)<\/td><td style=\"width: 34.2912%; height: 53px;\">$12.211.650<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a83728 e-con-full e-flex e-con e-child\" data-id=\"3a83728\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7535041 elementor-widget elementor-widget-text-editor\" data-id=\"7535041\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0Programas de posgrado, por ciclo acad\u00e9mico, para estudiantes <strong>antiguos que mantenga continuidad.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cba0cd6 elementor-widget elementor-widget-text-editor\" data-id=\"cba0cd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 0%; height: 19px;\">Especializaci\u00f3n en Bienestar Animal y Etolog\u00eda (Virtual)<\/td><td style=\"width: 34.2912%; height: 19px;\">$7.625.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Derecho Procesal<\/td><td style=\"width: 34.2912%; height: 53px;\">$8.983.350<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Educaci\u00f3n en Contextos Rurales (Virtual)<\/td><td style=\"width: 34.2912%; height: 53px;\">$3.848.500<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Gesti\u00f3n de Agronegocios (Virtual)<\/td><td style=\"width: 34.2912%; height: 53px;\">$4.447.800<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Legislaci\u00f3n Rural y Ordenamiento Territorial (Registro \u00danico)<\/td><td style=\"width: 34.2912%; height: 53px;\">$8.983.350<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Responsabilidad Ambiental y Sostenibilidad (Presencial)<\/td><td style=\"width: 34.2912%; height: 53px;\">$8.472.550<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Salud Publica Veterinaria (Virtual)<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.625.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Seguridad Industrial, Higiene y Gesti\u00f3n Ambiental (Presencial)<\/td><td style=\"width: 34.2912%; height: 53px;\">$6.466.900<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Especializaci\u00f3n en Sistemas de Gesti\u00f3n Integrada de la Calidad, Medio Ambiente y Prevenci\u00f3n de Riesgos Laborales (Presencial)<\/td><td style=\"width: 34.2912%; height: 53px;\">$7.950.100<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Maestr\u00eda en Ingenier\u00eda (Presencial)<\/td><td style=\"width: 34.2912%; height: 53px;\">$12.211.650<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b49337 e-flex e-con-boxed e-con e-parent\" data-id=\"9b49337\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4718415 e-con-full e-flex e-con e-child\" data-id=\"4718415\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5489969 e-con-full e-flex e-con e-child\" data-id=\"5489969\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73844d3 elementor-widget elementor-widget-heading\" data-id=\"73844d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Valores de Cr\u00e9ditos Adicionales Pregrado<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-936505e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"936505e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca74df1 e-con-full e-flex e-con e-child\" data-id=\"ca74df1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9179a7d e-con-full e-flex e-con e-child\" data-id=\"9179a7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5f43bea e-con-full e-flex e-con e-child\" data-id=\"5f43bea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2191f98 elementor-widget elementor-widget-text-editor\" data-id=\"2191f98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Te\u00f3rico de programas de pregrado<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c13dad elementor-widget elementor-widget-text-editor\" data-id=\"7c13dad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 0%; height: 19px;\"><span style=\"font-size: 12pt;\">Administraci\u00f3n de Empresas<\/span><\/td><td style=\"width: 34.2912%; height: 19px;\">$129.750<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Administraci\u00f3n financiera y de Sistemas<\/td><td style=\"width: 34.2912%; height: 53px;\">$285.360<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Contadur\u00eda P\u00fablica<\/td><td style=\"width: 34.2912%; height: 53px;\">$293.150<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Derecho<\/td><td style=\"width: 34.2912%; height: 53px;\">$363.750<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Agroindustrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$252.000<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Ambiental<\/td><td style=\"width: 34.2912%; height: 53px;\">$182.600<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Civil<\/td><td style=\"width: 34.2912%; height: 53px;\">$274.700<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Alimentos<\/td><td style=\"width: 34.2912%; height: 53px;\">$319.850<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Industrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$310.250<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Mecatr\u00f3nica<\/td><td style=\"width: 34.2912%; height: 53px;\">$297.250<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Medicina Veterinaria<\/td><td style=\"width: 34.2912%; height: 53px;\">$249.400<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Zootecnia<\/td><td style=\"width: 34.2912%; height: 53px;\">$249.500<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Electiva no ofertada en planes de estudio de pregrado<\/td><td style=\"width: 34.2912%; height: 53px;\">$274.700<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b789519 e-con-full e-flex e-con e-child\" data-id=\"b789519\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-933834b elementor-widget elementor-widget-text-editor\" data-id=\"933834b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Te\u00f3rico &#8211; Pr\u00e1ctico de programas de pregrado<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-274c53f elementor-widget elementor-widget-text-editor\" data-id=\"274c53f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Administraci\u00f3n de Empresas<\/td><td style=\"width: 34.2912%; height: 53px;\">$259.500<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Derecho<\/td><td style=\"width: 34.2912%; height: 53px;\">$724.250<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Agroindustrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$502.800<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Ambiental<\/td><td style=\"width: 34.2912%; height: 53px;\">$350.700<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Civil<\/td><td style=\"width: 34.2912%; height: 53px;\">$548.100<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Alimentos<\/td><td style=\"width: 34.2912%; height: 53px;\">$505.500<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Industrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$620.600<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Mecatr\u00f3nica<\/td><td style=\"width: 34.2912%; height: 53px;\">$528.100<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Medicina Veterinaria<\/td><td style=\"width: 34.2912%; height: 53px;\">$498.850<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Zootecnia<\/td><td style=\"width: 34.2912%; height: 53px;\">$565.500<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Electiva no ofertada en planes de estudio de pregrado<\/td><td style=\"width: 34.2912%; height: 53px;\">$541.450<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4d519b e-con-full e-flex e-con e-child\" data-id=\"b4d519b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b9c1aaa e-con-full e-flex e-con e-child\" data-id=\"b9c1aaa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-436a449 elementor-widget elementor-widget-text-editor\" data-id=\"436a449\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Pr\u00e1ctico de programas de pregrado<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-860492f elementor-widget elementor-widget-text-editor\" data-id=\"860492f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 0%; height: 19px;\"><span style=\"font-size: 12pt;\">Ingenier\u00eda Agroindustrial<\/span><\/td><td style=\"width: 34.2912%; height: 19px;\">$753.600<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda de Alimentos<\/td><td style=\"width: 34.2912%; height: 53px;\">$758.950<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Medicina Veterinaria<\/td><td style=\"width: 34.2912%; height: 53px;\">$746.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Zootecnia<\/td><td style=\"width: 34.2912%; height: 53px;\">$848.250<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Electiva no ofertada en planes de estudio de pregrado<\/td><td style=\"width: 34.2912%; height: 53px;\">$777.600<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab07ead e-con-full e-flex e-con e-child\" data-id=\"ab07ead\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1764fb7 e-flex e-con-boxed e-con e-parent\" data-id=\"1764fb7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9d26ed0 e-con-full e-flex e-con e-child\" data-id=\"9d26ed0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-332db02 e-con-full e-flex e-con e-child\" data-id=\"332db02\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7055f9b elementor-widget elementor-widget-heading\" data-id=\"7055f9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Valores de Cr\u00e9ditos Adicionales Posgrado<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5004ca2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5004ca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f9ac2d e-con-full e-flex e-con e-child\" data-id=\"4f9ac2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f70d692 e-con-full e-flex e-con e-child\" data-id=\"f70d692\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2712fe8 e-con-full e-flex e-con e-child\" data-id=\"2712fe8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f846d9 elementor-widget elementor-widget-text-editor\" data-id=\"9f846d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Te\u00f3rico de programas de Posgrado<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8d87ba elementor-widget elementor-widget-text-editor\" data-id=\"c8d87ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 97.7544%; height: 549px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 19px;\">Especializaci\u00f3n en Bienestar Animal y Etolog\u00eda<\/td><td style=\"width: 10.8908%;\">$524.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Legislaci\u00f3n Rural y Ordenamiento Territorial<\/td><td style=\"width: 10.8908%; height: 53px;\">$682.800<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Responsabilidad Ambiental y Sostenibilidad<\/td><td style=\"width: 10.8908%;\">$665.750<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Salud Publica Veterinaria<\/td><td style=\"width: 10.8908%;\">$524.950<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Sistemas de Gesti\u00f3n Integrada de la Calidad, Medio ambiente y Prevenci\u00f3n de Riesgos Laborales.<\/td><td style=\"width: 10.8908%; height: 53px;\">$691.400<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Seguridad Industrial, Higiene y Gesti\u00f3n Ambiental<\/td><td style=\"width: 10.8908%;\">$528.650<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Gesti\u00f3n de Agronegocios<\/td><td style=\"width: 10.8908%;\">$544.500<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Educaci\u00f3n en Contextos Rurales<\/td><td style=\"width: 10.8908%;\">$455.150<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Maestr\u00eda en Ingenier\u00eda<\/td><td style=\"width: 10.8908%; height: 53px;\">$1.169.900<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Derecho Procesal Agrario<\/td><td style=\"width: 10.8908%; height: 53px;\">$642.450<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Electivas no ofertadas en los planes de estudio (posgrados)<\/td><td style=\"width: 10.8908%; height: 53px;\">$643.700<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4322061 e-con-full e-flex e-con e-child\" data-id=\"4322061\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f0c773 elementor-widget elementor-widget-text-editor\" data-id=\"0f0c773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Te\u00f3rico &#8211; Pr\u00e1ctico de programas de Posgrado<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40e6c59 elementor-widget elementor-widget-text-editor\" data-id=\"40e6c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 97.7544%; height: 549px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 65.0513%; height: 19px;\">Especializaci\u00f3n en Bienestar Animal y Etolog\u00eda<\/td><td style=\"width: 13.1142%;\">$1.049.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.0513%; height: 53px;\">Especializaci\u00f3n en Salud Publica Veterinaria<\/td><td style=\"width: 13.1142%; height: 53px;\">$1.049.950<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.0513%; height: 53px;\">Especializaci\u00f3n en Sistemas de Gesti\u00f3n Integrada de la Calidad, Medio Ambiente y Prevenci\u00f3n de Riesgos Laborales<\/td><td style=\"width: 13.1142%;\">$1.381.650<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.0513%; height: 53px;\">Especializaci\u00f3n en Seguridad Industrial, Higiene y Gesti\u00f3n Ambiental<\/td><td style=\"width: 13.1142%;\">$1.054.850<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.0513%; height: 53px;\">Electivas no ofertadas en los planes de estudio (posgrados)<\/td><td style=\"width: 13.1142%; height: 53px;\">$1.134.400<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0cd38d5 e-con-full e-flex e-con e-child\" data-id=\"0cd38d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c07aaae e-con-full e-flex e-con e-child\" data-id=\"c07aaae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d821da elementor-widget elementor-widget-text-editor\" data-id=\"1d821da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Pr\u00e1ctico de programas de Posgrado<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52713b1 elementor-widget elementor-widget-text-editor\" data-id=\"52713b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 99.064%; height: 47px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 66.6599%; height: 19px;\">Electivas no ofertadas en los planes de estudio (posgrados)<\/td><td style=\"width: 11.5056%;\">$677.250<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-370c8cf e-con-full e-flex e-con e-child\" data-id=\"370c8cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42bf550 e-flex e-con-boxed e-con e-parent\" data-id=\"42bf550\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-811f2bf e-con-full e-flex e-con e-child\" data-id=\"811f2bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-757ff36 e-con-full e-flex e-con e-child\" data-id=\"757ff36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8a9ac9 elementor-widget elementor-widget-heading\" data-id=\"b8a9ac9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Valor cr\u00e9ditos acad\u00e9micos de cursos libres homologables<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9faea2a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9faea2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bdeba3 e-con-full e-flex e-con e-child\" data-id=\"3bdeba3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a9ccb3 e-con-full e-flex e-con e-child\" data-id=\"3a9ccb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-02ae240 e-con-full e-flex e-con e-child\" data-id=\"02ae240\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23456c9 elementor-widget elementor-widget-text-editor\" data-id=\"23456c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Te\u00f3rico de <strong>pregrado<\/strong> y dependencias transversales<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2def399 elementor-widget elementor-widget-text-editor\" data-id=\"2def399\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\"><span style=\"font-size: 12pt;\">Administraci\u00f3n de Empresas<\/span><\/td><td style=\"width: 34.2912%; height: 53px;\">$143.450<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Administraci\u00f3n Financiera y de Sistemas<\/td><td style=\"width: 34.2912%; height: 53px;\">$313.200<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\"><span style=\"font-size: 12pt;\">Contadur\u00eda publica<\/span><\/td><td style=\"width: 34.2912%; height: 53px;\">$322.000<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Derecho<\/td><td style=\"width: 34.2912%; height: 53px;\">$398.900<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Agroindustrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$277.700<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Alimentos<\/td><td style=\"width: 34.2912%; height: 53px;\">$278.900<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Ambiental<\/td><td style=\"width: 34.2912%; height: 53px;\">$201.850<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Industrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$341.350<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Mecatr\u00f3nica<\/td><td style=\"width: 34.2912%; height: 53px;\">$291.150<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Civil<\/td><td style=\"width: 34.2912%; height: 53px;\">$305.950<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Medicina Veterinaria<\/td><td style=\"width: 34.2912%; height: 53px;\">$275.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Zootecnia<\/td><td style=\"width: 34.2912%; height: 53px;\">$310.800<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Departamento de Ciencias B\u00e1sicas<\/td><td style=\"width: 34.2912%; height: 53px;\">$275.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Departamento de Humanidades<\/td><td style=\"width: 34.2912%; height: 53px;\">$275.300<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Centro de Emprendimiento y Desarrollo Empresarial<\/td><td style=\"width: 34.2912%; height: 53px;\">$275.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Institutos de Idiomas<\/td><td style=\"width: 34.2912%; height: 53px;\">$535.950<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Electiva no ofertada en planes de estudio de pregrado<\/td><td style=\"width: 34.2912%; height: 53px;\">$302.200<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7f9c1a e-con-full e-flex e-con e-child\" data-id=\"d7f9c1a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc7317 elementor-widget elementor-widget-text-editor\" data-id=\"5dc7317\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Te\u00f3rico &#8211; Pr\u00e1ctico de <strong>pregrado<\/strong> y dependencias transversales<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-154daa7 elementor-widget elementor-widget-text-editor\" data-id=\"154daa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 100%; height: 496px;\"><tbody><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\"><span style=\"font-size: 12pt;\">Administraci\u00f3n de Empresas<\/span><\/td><td style=\"width: 34.2912%; height: 53px;\">$190.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Derecho<\/td><td style=\"width: 34.2912%; height: 53px;\">$796.650<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Agroindustrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$553.100<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Ambiental<\/td><td style=\"width: 34.2912%; height: 53px;\">$401.350<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Civil<\/td><td style=\"width: 34.2912%; height: 53px;\">$603.300<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Alimentos<\/td><td style=\"width: 34.2912%; height: 53px;\">$556.750<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Industrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$682.800<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Mecatr\u00f3nica<\/td><td style=\"width: 34.2912%; height: 53px;\">$581.250<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Medicina Veterinaria<\/td><td style=\"width: 34.2912%; height: 53px;\">$548.200<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Zootecnia<\/td><td style=\"width: 34.2912%; height: 53px;\">$621.650<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Departamento de Ciencias B\u00e1sicas<\/td><td style=\"width: 34.2912%; height: 53px;\">$474.800<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Departamento de Humanidades<\/td><td style=\"width: 34.2912%; height: 53px;\">$474.800<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Centro de Emprendimiento y Desarrollo Empresarial<\/td><td style=\"width: 34.2912%; height: 53px;\">$474.800<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Electiva no ofertada en planes de estudio de pregrado<\/td><td style=\"width: 34.2912%; height: 53px;\">$595.950<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5375bc e-con-full e-flex e-con e-child\" data-id=\"b5375bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1161509 e-con-full e-flex e-con e-child\" data-id=\"1161509\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b52e72f elementor-widget elementor-widget-text-editor\" data-id=\"b52e72f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Pr\u00e1ctico de <strong>pregrado<\/strong> y dependencias transversales<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c8e1e0 elementor-widget elementor-widget-text-editor\" data-id=\"8c8e1e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 98.9711%; height: 364px;\"><tbody><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Administraci\u00f3n de Empresas<\/td><td style=\"width: 34.2912%; height: 53px;\">$285.900<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Agroindustrial<\/td><td style=\"width: 34.2912%; height: 53px;\">$829.750<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Ingenier\u00eda Alimentos<\/td><td style=\"width: 34.2912%; height: 53px;\">$834.600<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">Medicina Veterinaria<\/td><td style=\"width: 34.2912%; height: 53px;\">$821.150<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.7088%; height: 53px;\">Zootecnia<\/td><td style=\"width: 34.2912%; height: 53px;\">$933.700<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.7088%; height: 53px;\">electiva no ofertada en planes de estudio de pregrado<\/td><td style=\"width: 34.2912%; height: 53px;\">$855.400<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96c1679 e-con-full e-flex e-con e-child\" data-id=\"96c1679\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97bb086 e-con-full e-flex e-con e-child\" data-id=\"97bb086\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-53e9985 e-con-full e-flex e-con e-child\" data-id=\"53e9985\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da3a13e elementor-widget elementor-widget-text-editor\" data-id=\"da3a13e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Te\u00f3rico de programas de <strong>posgrado<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-502a9bb elementor-widget elementor-widget-text-editor\" data-id=\"502a9bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 97.7544%; height: 549px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 19px;\">Especializaci\u00f3n en Bienestar Animal y Etolog\u00eda<\/td><td style=\"width: 10.8908%;\">$498.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Legislaci\u00f3n Rural y Ordenamiento Territorial<\/td><td style=\"width: 10.8908%; height: 53px;\">$648.950<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Responsabilidad Ambiental y Sostenibilidad<\/td><td style=\"width: 10.8908%;\">$632.700<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Salud Publica Veterinaria<\/td><td style=\"width: 10.8908%;\">$498.950<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Sistemas de Gesti\u00f3n Integrada de la Calidad, Medio ambiente y Prevenci\u00f3n de Riesgos Laborales.<\/td><td style=\"width: 10.8908%; height: 53px;\">$657.150<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Seguridad Industrial, Higiene y Gesti\u00f3n Ambiental<\/td><td style=\"width: 10.8908%;\">$502.400<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Gesti\u00f3n de Agronegocios<\/td><td style=\"width: 10.8908%;\">$517.550<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Educaci\u00f3n en Contextos Rurales<\/td><td style=\"width: 10.8908%;\">$432.650<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Maestr\u00eda en Ingenier\u00eda<\/td><td style=\"width: 10.8908%; height: 53px;\">$1.111.900<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Especializaci\u00f3n en Derecho Procesal Agrario<\/td><td style=\"width: 10.8908%; height: 53px;\">$706.850<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Electivas no ofertadas en los planes de estudio (posgrados)<\/td><td style=\"width: 10.8908%; height: 53px;\">$611.750<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e830f4c e-con-full e-flex e-con e-child\" data-id=\"e830f4c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee9850a elementor-widget elementor-widget-text-editor\" data-id=\"ee9850a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Te\u00f3rico &#8211; Pr\u00e1ctico de programas de <strong>posgrado<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b49b6d elementor-widget elementor-widget-text-editor\" data-id=\"6b49b6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 97.7544%; height: 549px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 65.0513%; height: 19px;\">Especializaci\u00f3n en Bienestar Animal y Etolog\u00eda<\/td><td style=\"width: 13.1142%;\">$997.900<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.0513%; height: 53px;\">Especializaci\u00f3n en Salud Publica Veterinaria<\/td><td style=\"width: 13.1142%; height: 53px;\">$997.900<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.0513%; height: 53px;\">Especializaci\u00f3n en Sistemas de Gesti\u00f3n Integrada de la Calidad, Medio Ambiente y Prevenci\u00f3n de Riesgos Laborales<\/td><td style=\"width: 13.1142%;\">$1.313.150<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 65.0513%; height: 53px;\">Especializaci\u00f3n en Seguridad Industrial, Higiene y Gesti\u00f3n Ambiental<\/td><td style=\"width: 13.1142%;\">$1.002.600<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 65.0513%; height: 53px;\">Electivas no ofertadas en los planes de estudio (posgrados)<\/td><td style=\"width: 13.1142%; height: 53px;\">$1.078.200<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d14bb8 e-con-full e-flex e-con e-child\" data-id=\"6d14bb8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-07baeda e-con-full e-flex e-con e-child\" data-id=\"07baeda\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d9350c elementor-widget elementor-widget-text-editor\" data-id=\"0d9350c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Componente Pr\u00e1ctico de programas de <strong>Posgrado<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9278b73 elementor-widget elementor-widget-text-editor\" data-id=\"9278b73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table style=\"border-collapse: collapse; width: 99.064%; height: 47px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 66.6599%; height: 19px;\">Electivas no ofertadas en los planes de estudio (posgrados)<\/td><td style=\"width: 11.5056%;\">$611.750<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7636c9d e-con-full e-flex e-con e-child\" data-id=\"7636c9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-430feb5 e-flex e-con-boxed e-con e-parent\" data-id=\"430feb5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e542250 e-con-full e-flex e-con e-child\" data-id=\"e542250\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-858e424 e-con-full e-flex e-con e-child\" data-id=\"858e424\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-367af53 elementor-widget elementor-widget-heading\" data-id=\"367af53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Otros Valores 2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f39b073 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f39b073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7654e0 e-con-full e-flex e-con e-child\" data-id=\"e7654e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f4979f elementor-widget elementor-widget-image\" data-id=\"8f4979f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"645\" src=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/02\/8-4-1024x645.png\" class=\"attachment-large size-large wp-image-57654\" alt=\"\" srcset=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/02\/8-4-1024x645.png 1024w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/02\/8-4-300x189.png 300w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/02\/8-4-768x484.png 768w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/02\/8-4.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-852993c e-con-full e-flex e-con e-child\" data-id=\"852993c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-05e07e2 e-con-full e-flex e-con e-child\" data-id=\"05e07e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea42334 elementor-widget elementor-widget-text-editor\" data-id=\"ea42334\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Inscripci\u00f3n<\/strong><\/p><table style=\"border-collapse: collapse; width: 88.1485%; height: 0px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 19px;\">Pregrado<\/td><td style=\"width: 10.8908%;\">$52.600<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Posgrado<\/td><td style=\"width: 10.8908%; height: 53px;\">$219.000<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-161c786 elementor-widget elementor-widget-text-editor\" data-id=\"161c786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Cursos intensivos o vacacionales<\/strong><\/p><table style=\"border-collapse: collapse; width: 89.5852%; height: 0px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 19px;\">Curso vacacional de asignaturas te\u00f3ricas<\/td><td style=\"width: 43.4615%;\">$1.051.700<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Curso vacacional de asignaturas practicas<\/td><td style=\"width: 43.4615%; height: 53px;\">$1.229.100<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Curso preparatorio<\/td><td style=\"width: 43.4615%;\">$888.250<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Curso intensivo de segunda lengua<\/td><td style=\"width: 43.4615%;\">$535.500<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e22312 elementor-widget elementor-widget-text-editor\" data-id=\"1e22312\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ex\u00e1menes Posgrado 2026<\/strong><\/p><table style=\"border-collapse: collapse; width: 89.5852%; height: 0px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 79.511%; height: 19px;\">Examen supletorio (programas de posgrado)<\/td><td style=\"width: 31.2252%;\">$139.100<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 79.511%; height: 53px;\">Examen de suficiencia (programas de posgrado)<\/td><td style=\"width: 31.2252%; height: 53px;\">$210.900<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 79.511%; height: 53px;\">Examen preparatorio (programas de posgrado)<\/td><td style=\"width: 31.2252%;\">$239.550<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 79.511%; height: 53px;\">Examen de validaci\u00f3n de conocimientos (programas de posgrado)<\/td><td style=\"width: 31.2252%;\">$239.550<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a72c3fe elementor-widget elementor-widget-text-editor\" data-id=\"a72c3fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Otros servicios 2026<\/strong><\/p><table style=\"border-collapse: collapse; width: 97.7544%; height: 385px;\"><tbody><tr style=\"height: 48px;\"><td style=\"width: 67.2747%; height: 48px;\">Duplicado del carn\u00e9<\/td><td style=\"width: 10.8908%; height: 48px;\">$35.000<\/td><\/tr><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 19px;\">Duplicado del Acta de Grado<\/td><td style=\"width: 10.8908%; height: 19px;\">$111.950<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Duplicado del diploma de grado<\/td><td style=\"width: 10.8908%; height: 53px;\">$222.700<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Certificado Financiero<\/td><td style=\"width: 10.8908%; height: 53px;\">$21.750<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Carn\u00e9 de visitante<\/td><td style=\"width: 10.8908%; height: 53px;\">$12.950<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Multa Biblioteca (por d\u00eda)<\/td><td style=\"width: 10.8908%; height: 53px;\">$4.100<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Multa Laboratorio<\/td><td style=\"width: 10.8908%; height: 53px;\">$4.100<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Repetici\u00f3n Nivel segunda lengua<\/td><td style=\"width: 10.8908%; height: 53px;\">$608.950<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7438e73 e-con-full e-flex e-con e-child\" data-id=\"7438e73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13609be elementor-widget elementor-widget-text-editor\" data-id=\"13609be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ex\u00e1menes Pregrado 2026<\/strong><\/p><table style=\"border-collapse: collapse; width: 89.5852%; height: 0px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 19px;\">Examen supletorio (programas de pregrado)<\/td><td style=\"width: 43.4615%;\">$141.500<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Examen de suficiencia (programas de pregrado)<\/td><td style=\"width: 43.4615%; height: 53px;\">$214.550<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Examen preparatorio (programas de pregrado)<\/td><td style=\"width: 43.4615%;\">$243.700<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Examen de validaci\u00f3n de conocimientos (programas de pregrado)<\/td><td style=\"width: 43.4615%;\">$243.700<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-da0d812 e-con-full e-flex e-con e-child\" data-id=\"da0d812\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f8a968 elementor-widget elementor-widget-text-editor\" data-id=\"7f8a968\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Certificados y constancias 2026<\/strong><\/p><p>\u00a0<\/p><table style=\"border-collapse: collapse; width: 89.5852%; height: 0px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 19px;\">Constancia de estudio<\/td><td style=\"width: 43.4615%;\">$18.100<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Certificaci\u00f3n de contenido program\u00e1tico<\/td><td style=\"width: 43.4615%; height: 53px;\">$21.750<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Certificaci\u00f3n especial<\/td><td style=\"width: 43.4615%;\">$21.750<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">constancias y certificaciones acad\u00e9micas complementarias y\/o personalizadas<\/td><td style=\"width: 43.4615%; height: 53px;\">$30.000<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f9a45c elementor-widget elementor-widget-text-editor\" data-id=\"0f9a45c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Otros derechos pecuniarios 2026<\/strong><\/p><table style=\"border-collapse: collapse; width: 89.5852%; height: 0px;\"><tbody><tr style=\"height: 44px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 19px;\">Derecho de grado ceremonia colectiva (pregrado y posgrado)<\/td><td style=\"width: 43.4615%;\">0.8 SMLV*<\/td><\/tr><tr style=\"height: 53px;\"><td style=\"width: 67.2747%; height: 53px;\">Derecho de grado privado\u00a0 (pregrado y posgrado)<\/td><td style=\"width: 43.4615%; height: 53px;\">0.8 SMLV*<\/td><\/tr><tr style=\"height: 53px; background-color: #f5ffc4;\"><td style=\"width: 67.2747%; height: 53px;\">Curso de profundizaci\u00f3n como opci\u00f3n de grado (pregrado)<\/td><td style=\"width: 43.4615%;\">$6.731.000<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-112e34f e-con-full e-flex e-con e-parent\" data-id=\"112e34f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-376752f e-con-full e-flex e-con e-child\" data-id=\"376752f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-51453b3 e-flex e-con-boxed e-con e-child\" data-id=\"51453b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f103cb2 e-con-full e-flex e-con e-child\" data-id=\"f103cb2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c869a5 elementor-widget elementor-widget-text-editor\" data-id=\"8c869a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Oficina Atenci\u00f3n al Aspirante, comun\u00edcate a<\/h3><h3 class=\"elementor-icon-box-title\">Admisiones<\/h3><p class=\"elementor-icon-box-description\">+(57) 313 423 06 49<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-078d72f e-con-full e-flex e-con e-child\" data-id=\"078d72f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c682e2 elementor-widget elementor-widget-image\" data-id=\"9c682e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"615\" src=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2024\/12\/curso-contaduria-publica-imagen-referencia-03-768x615.png\" class=\"attachment-medium_large size-medium_large wp-image-50137\" alt=\"\" srcset=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2024\/12\/curso-contaduria-publica-imagen-referencia-03-768x615.png 768w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2024\/12\/curso-contaduria-publica-imagen-referencia-03-300x240.png 300w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2024\/12\/curso-contaduria-publica-imagen-referencia-03-1024x819.png 1024w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2024\/12\/curso-contaduria-publica-imagen-referencia-03.png 1466w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a0Valor de las Matr\u00edculas Estudia a un costo Accesible Acuerdo No. 1198 del 12 de noviembre de 2025 &#8211; por el cual se establecen los valores de matr\u00edcula y otros derechos pecuniarios para los estudiantes de UNIAGRARIA para el a\u00f1o 2026 Pregrado Programas de pregrado, por ciclo acad\u00e9mico, para los estudiantes de PRIMERA MATR\u00cdCULA en [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-57630","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valor Matr\u00edculas - UNIAGRARIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valor Matr\u00edculas - UNIAGRARIA\" \/>\n<meta property=\"og:description\" content=\"\u00a0Valor de las Matr\u00edculas Estudia a un costo Accesible Acuerdo No. 1198 del 12 de noviembre de 2025 &#8211; por el cual se establecen los valores de matr\u00edcula y otros derechos pecuniarios para los estudiantes de UNIAGRARIA para el a\u00f1o 2026 Pregrado Programas de pregrado, por ciclo acad\u00e9mico, para los estudiantes de PRIMERA MATR\u00cdCULA en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIAGRARIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T16:19:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/elementor\/thumbs\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/valor-matriculas\\\/\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/valor-matriculas\\\/\",\"name\":\"Valor Matr\u00edculas - UNIAGRARIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/valor-matriculas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/valor-matriculas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png\",\"datePublished\":\"2025-02-28T02:09:03+00:00\",\"dateModified\":\"2025-11-27T16:19:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/valor-matriculas\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/valor-matriculas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/valor-matriculas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png\",\"contentUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/valor-matriculas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valor Matr\u00edculas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"name\":\"UNIAGRARIA\",\"description\":\"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\",\"name\":\"UNIAGRARIA\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"contentUrl\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"width\":3300,\"height\":2550,\"caption\":\"UNIAGRARIA\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uagraria\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/UNIAGRARIA\",\"https:\\\/\\\/www.instagram.com\\\/uniagraria\\\/profilecard\\\/?igsh=MXI2bTFlMWsxNzNjOA\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/uniagraria?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/uniagraria\\\/?originalSubdomain=co\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UniagrariaUverde?themeRefresh=1\",\"https:\\\/\\\/api.whatsapp.com\\\/send?phone=3134230649\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valor Matr\u00edculas - UNIAGRARIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/","og_locale":"es_ES","og_type":"article","og_title":"Valor Matr\u00edculas - UNIAGRARIA","og_description":"\u00a0Valor de las Matr\u00edculas Estudia a un costo Accesible Acuerdo No. 1198 del 12 de noviembre de 2025 &#8211; por el cual se establecen los valores de matr\u00edcula y otros derechos pecuniarios para los estudiantes de UNIAGRARIA para el a\u00f1o 2026 Pregrado Programas de pregrado, por ciclo acad\u00e9mico, para los estudiantes de PRIMERA MATR\u00cdCULA en [&hellip;]","og_url":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/","og_site_name":"UNIAGRARIA","article_publisher":"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","article_modified_time":"2025-11-27T16:19:38+00:00","og_image":[{"url":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/elementor\/thumbs\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@UNIAGRARIA","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/","url":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/","name":"Valor Matr\u00edculas - UNIAGRARIA","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/#primaryimage"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/#primaryimage"},"thumbnailUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/elementor\/thumbs\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png","datePublished":"2025-02-28T02:09:03+00:00","dateModified":"2025-11-27T16:19:38+00:00","breadcrumb":{"@id":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/#primaryimage","url":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/elementor\/thumbs\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png","contentUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/elementor\/thumbs\/2-9-rcmeo21r8mv6tq0ro9auvi4a03khtl9blysr2vub20.png"},{"@type":"BreadcrumbList","@id":"https:\/\/uniagraria.edu.co\/es\/valor-matriculas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/uniagraria.edu.co\/"},{"@type":"ListItem","position":2,"name":"Valor Matr\u00edculas"}]},{"@type":"WebSite","@id":"https:\/\/uniagraria.edu.co\/es\/#website","url":"https:\/\/uniagraria.edu.co\/es\/","name":"UNIAGRARIA","description":"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA","publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniagraria.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/uniagraria.edu.co\/es\/#organization","name":"UNIAGRARIA","url":"https:\/\/uniagraria.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","contentUrl":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","width":3300,"height":2550,"caption":"UNIAGRARIA"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","https:\/\/x.com\/UNIAGRARIA","https:\/\/www.instagram.com\/uniagraria\/profilecard\/?igsh=MXI2bTFlMWsxNzNjOA","https:\/\/www.tiktok.com\/discover\/uniagraria?lang=es","https:\/\/www.linkedin.com\/school\/uniagraria\/?originalSubdomain=co","https:\/\/www.youtube.com\/user\/UniagrariaUverde?themeRefresh=1","https:\/\/api.whatsapp.com\/send?phone=3134230649"]}]}},"_links":{"self":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/pages\/57630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/comments?post=57630"}],"version-history":[{"count":0,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/pages\/57630\/revisions"}],"wp:attachment":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/media?parent=57630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}