{"id":47734,"date":"2025-03-07T14:45:02","date_gmt":"2025-03-07T19:45:02","guid":{"rendered":"https:\/\/www.uniagraria.edu.co\/?p=47734"},"modified":"2025-03-07T14:45:02","modified_gmt":"2025-03-07T19:45:02","slug":"uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador","status":"publish","type":"post","link":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/","title":{"rendered":"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\" id=\"mce_0\"><strong>Direcci\u00f3n de Comunicaciones UNIAGRARIA\ufeff<\/strong><\/h4>\n\n\n\n<p style=\"text-align: justify;\">El pasado 7 de marzo de 2025, UNIAGRARIA celebr\u00f3 con orgullo el D\u00eda del Fundador, un evento en el que se rindi\u00f3 homenaje a quienes hicieron posible la creaci\u00f3n de esta instituci\u00f3n, que hoy cumple cuatro d\u00e9cadas de compromiso con la educaci\u00f3n superior y el desarrollo del campo colombiano. En esta ocasi\u00f3n especial, el Vicerrector de Investigaci\u00f3n, Dr. \u00c1lvaro Mauricio Z\u00fa\u00f1iga Morales, comparti\u00f3 unas palabras de conmemoraci\u00f3n, exaltando el legado de los fundadores y los logros alcanzados en estos 40 a\u00f1os de trayectoria. A continuaci\u00f3n, su discurso:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Palabras de conmemoraci\u00f3n de los 40 a\u00f1os de UNIAGRARIA Marzo 07 de 2025<\/strong><\/h4>\n\n\n\n<p style=\"text-align: justify;\">&#8220;Dra. Teresa Ar\u00e9valo Ram\u00edrez, Dra. Teresa Escobar de Torres, Dr. H\u00e9ctor Jairo Guar\u00edn Avellaneda, Dr. Alvaro Ram\u00edrez Rubiano, Dr. Jorge Orlando Gait\u00e1n Arciniegas, Dr. \u00c1lvaro Zu\u00f1iga Garc\u00eda y a la memoria y legado del Dr. Emiro Mart\u00ednez Jim\u00e9nez y del Dr. Alfredo Arbel\u00e1ez Herrera.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Hay momentos en la vida en que debemos celebrar, conmemorar y honrar, y hoy es uno de esos d\u00edas en los cuales celebramos y conmemoramos una fecha trascendental para todos los aqu\u00ed presentes; para nuestros estudiantes, para nuestros docentes, para nuestros egresados, para nuestro equipo administrativo, para los campesinos de Colombia e indudablemente para honrar a nuestros Fundadores.<\/p>\n\n\n\n<p style=\"text-align: justify;\">El 8 de marzo de 1985 nace para la sociedad la Fundaci\u00f3n Universitaria Agraria de Colombia \u2013 UNIAGRARIA. Una Instituci\u00f3n de Educaci\u00f3n Superior fundada hace 40 a\u00f1os con la loable misi\u00f3n de contribuir al desarrollo humano del campesino colombiano, basada nuestra misi\u00f3n en tres pilares que nuestros Fundadores visionaron con claridad casi prof\u00e9tica y clarividente y hoy tanto o m\u00e1s pertinente que hace 40 a\u00f1os: el Desarrollo Regional con Enfoque Territorial, la Sostenibilidad Ambiental y la Cultura del Emprendimiento.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Hoy Colombia cuenta con una instituci\u00f3n s\u00f3lida gracias a sus cimientos y al pensamiento visionario de sus Fundadores. Dos lemas han marcado el derrotero de UNIAGRARIA y en eso se ha convertido nuestra instituci\u00f3n: \u201cCiencia y Fe en el Campo\u201d y \u201cLa U Verde de Colombia\u201d.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Luego de 40 a\u00f1os de labores, UNIAGRARIA cuenta con programas acreditados de pregrado, programas de posgrado en los niveles de especializaci\u00f3n y maestr\u00eda. Tambi\u00e9n cuenta con proyectos que materializan la misi\u00f3n como UNIAGRARIA al Campo, Sembrar Paz, Plan 500 Colegios, UNIAGRARIA Acompa\u00f1a, Red de Colegios Verdes por la Sostenibilidad y con un proyecto prospectivo al a\u00f1o 2050 denominado Agroindustrial y Campesino (Modelo MACUA) que marca desde ya la l\u00ednea de direcci\u00f3n estrat\u00e9gica de la instituci\u00f3n para los pr\u00f3ximos 25 a\u00f1os.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Desde hace a\u00f1os la educaci\u00f3n virtual es parte fundamental del proceso formativo de nuestros estudiantes. Varios programas de especializaci\u00f3n se ofrecen de manera exitosa bajo la modalidad virtual y recientemente UNIAGRARIA obtuvo el Registro Calificado de su primer pregrado virtual en Administraci\u00f3n de Empresas. Nuevos retos, desaf\u00edos y oportunidades vendr\u00e1n con la virtualidad, que permite llegar de manera m\u00e1s expedita y clara con educaci\u00f3n de calidad a los territorios e incluso a otras latitudes.<\/p>\n\n\n\n<p style=\"text-align: justify;\">UNIAGRARIA est\u00e1 consolidando el Instituto T\u00e9cnico Uniagrarista (ITU) para ofrecer a la sociedad colombiana y de manera especial a la comunidad rural programas de educaci\u00f3n para el trabajo y el desarrollo humano, programas t\u00e9cnicos y tecnol\u00f3gicos dise\u00f1ados a la medida de las necesidades de las regiones.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Nuestra sede en el municipio de Facatativ\u00e1, el CIDT Pinares de Tenjo y el Centro Regional de Anolaima son la punta de lanza de la regionalizaci\u00f3n de UNIAGRARIA y hacen parte de los logros may\u00fasculos de nuestra universidad.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Con funciones sustantivas de la educaci\u00f3n superior plenamente desarrolladas y en constante madurez, UNIAGRARIA cuenta con Grupos de Investigaci\u00f3n categorizados ante MinCiencias, nuestros docentes y estudiantes publican y socializan sus desarrollos en investigaci\u00f3n, los cuales transfieren a trav\u00e9s de la extensi\u00f3n; adicionalmente, co-construyen con la comunidad en un modelo de h\u00e9lice m\u00faltiple conocimiento cient\u00edfico de la m\u00e1s alta calidad.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Con una infraestructura f\u00edsica y tecnol\u00f3gica acorde a las necesidades y que respalda la academia, un sistema acad\u00e9mico robusto (EPKUA), un \u00e1rea de comunicaciones y un \u00e1rea de mercadeo que consolidan la imagen corporativa y el posicionamiento de marca, UNIAGRARIA es cada vez m\u00e1s visible y reconocida.<\/p>\n\n\n\n<p style=\"text-align: justify;\">La internacionalizaci\u00f3n de UNIAGRARIA es pensada como un ejercicio formativo, pero tambi\u00e9n de cooperaci\u00f3n con el mundo y en especial con Latinoam\u00e9rica.<\/p>\n\n\n\n<p style=\"text-align: justify;\">UNIAGRARIA es y se proyecta como una instituci\u00f3n fiel a sus principios misionales y seguir\u00e1 siendo la instituci\u00f3n que emplea la educaci\u00f3n como medio para el desarrollo de las capacidades del habitante rural y contribuir a su felicidad.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Muchas gracias por su atenci\u00f3n. \u00a1Feliz Cumplea\u00f1os UNIAGRARIA!&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/03\/UniagrariaConmemora40AniosDeHistoria-01-1024x577.jpeg\" alt=\"\" class=\"wp-image-47733\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n de Comunicaciones UNIAGRARIA\ufeff El pasado 7 de marzo de 2025, UNIAGRARIA celebr\u00f3 con orgullo el D\u00eda del Fundador, un evento en el que se rindi\u00f3 homenaje a quienes hicieron posible la creaci\u00f3n de esta instituci\u00f3n, que hoy cumple cuatro d\u00e9cadas de compromiso con la educaci\u00f3n superior y el desarrollo del campo colombiano. En esta [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":47733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[35],"tags":[],"class_list":["post-47734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador - UNIAGRARIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador - UNIAGRARIA\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n de Comunicaciones UNIAGRARIA\ufeff El pasado 7 de marzo de 2025, UNIAGRARIA celebr\u00f3 con orgullo el D\u00eda del Fundador, un evento en el que se rindi\u00f3 homenaje a quienes hicieron posible la creaci\u00f3n de esta instituci\u00f3n, que hoy cumple cuatro d\u00e9cadas de compromiso con la educaci\u00f3n superior y el desarrollo del campo colombiano. En esta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIAGRARIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T19:45:02+00:00\" \/>\n<meta name=\"author\" content=\"Comunicaciones UNIAGRARIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:site\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones UNIAGRARIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/\"},\"author\":{\"name\":\"Comunicaciones UNIAGRARIA\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/f7d66f114fd9950dfb39f5c0a1ecb909\"},\"headline\":\"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador\",\"datePublished\":\"2025-03-07T19:45:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/\"},\"wordCount\":828,\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/\",\"name\":\"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador - UNIAGRARIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2025-03-07T19:45:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"name\":\"UNIAGRARIA\",\"description\":\"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\",\"name\":\"UNIAGRARIA\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"contentUrl\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"width\":3300,\"height\":2550,\"caption\":\"UNIAGRARIA\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uagraria\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/UNIAGRARIA\",\"https:\\\/\\\/www.instagram.com\\\/uniagraria\\\/profilecard\\\/?igsh=MXI2bTFlMWsxNzNjOA\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/uniagraria?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/uniagraria\\\/?originalSubdomain=co\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UniagrariaUverde?themeRefresh=1\",\"https:\\\/\\\/api.whatsapp.com\\\/send?phone=3134230649\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/f7d66f114fd9950dfb39f5c0a1ecb909\",\"name\":\"Comunicaciones UNIAGRARIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones UNIAGRARIA\"},\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/author\\\/4ndr3sf371p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador - UNIAGRARIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/","og_locale":"es_ES","og_type":"article","og_title":"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador - UNIAGRARIA","og_description":"Direcci\u00f3n de Comunicaciones UNIAGRARIA\ufeff El pasado 7 de marzo de 2025, UNIAGRARIA celebr\u00f3 con orgullo el D\u00eda del Fundador, un evento en el que se rindi\u00f3 homenaje a quienes hicieron posible la creaci\u00f3n de esta instituci\u00f3n, que hoy cumple cuatro d\u00e9cadas de compromiso con la educaci\u00f3n superior y el desarrollo del campo colombiano. En esta [&hellip;]","og_url":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/","og_site_name":"UNIAGRARIA","article_publisher":"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","article_published_time":"2025-03-07T19:45:02+00:00","author":"Comunicaciones UNIAGRARIA","twitter_card":"summary_large_image","twitter_creator":"@UNIAGRARIA","twitter_site":"@UNIAGRARIA","twitter_misc":{"Escrito por":"Comunicaciones UNIAGRARIA","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/#article","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/"},"author":{"name":"Comunicaciones UNIAGRARIA","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/f7d66f114fd9950dfb39f5c0a1ecb909"},"headline":"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador","datePublished":"2025-03-07T19:45:02+00:00","mainEntityOfPage":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/"},"wordCount":828,"publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/","url":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/","name":"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador - UNIAGRARIA","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/#primaryimage"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/#primaryimage"},"thumbnailUrl":"","datePublished":"2025-03-07T19:45:02+00:00","breadcrumb":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-conmemora-40-anos-de-historia-en-el-dia-del-fundador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/uniagraria.edu.co\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/uniagraria.edu.co\/es\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"UNIAGRARIA conmemora 40 a\u00f1os de historia en el D\u00eda del Fundador"}]},{"@type":"WebSite","@id":"https:\/\/uniagraria.edu.co\/es\/#website","url":"https:\/\/uniagraria.edu.co\/es\/","name":"UNIAGRARIA","description":"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA","publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniagraria.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/uniagraria.edu.co\/es\/#organization","name":"UNIAGRARIA","url":"https:\/\/uniagraria.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","contentUrl":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","width":3300,"height":2550,"caption":"UNIAGRARIA"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","https:\/\/x.com\/UNIAGRARIA","https:\/\/www.instagram.com\/uniagraria\/profilecard\/?igsh=MXI2bTFlMWsxNzNjOA","https:\/\/www.tiktok.com\/discover\/uniagraria?lang=es","https:\/\/www.linkedin.com\/school\/uniagraria\/?originalSubdomain=co","https:\/\/www.youtube.com\/user\/UniagrariaUverde?themeRefresh=1","https:\/\/api.whatsapp.com\/send?phone=3134230649"]},{"@type":"Person","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/f7d66f114fd9950dfb39f5c0a1ecb909","name":"Comunicaciones UNIAGRARIA","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","caption":"Comunicaciones UNIAGRARIA"},"url":"https:\/\/uniagraria.edu.co\/es\/author\/4ndr3sf371p3\/"}]}},"_links":{"self":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/47734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/comments?post=47734"}],"version-history":[{"count":0,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/47734\/revisions"}],"wp:attachment":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/media?parent=47734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/categories?post=47734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/tags?post=47734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}