{"id":49747,"date":"2025-05-02T17:58:48","date_gmt":"2025-05-02T22:58:48","guid":{"rendered":"https:\/\/www.uniagraria.edu.co\/?p=49747"},"modified":"2025-05-02T17:58:48","modified_gmt":"2025-05-02T22:58:48","slug":"reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta","status":"publish","type":"post","link":"https:\/\/uniagraria.edu.co\/es\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/","title":{"rendered":"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\" id=\"mce_0\"><strong>Direcci\u00f3n de Comunicaciones UNIAGRARIA<\/strong><\/h4>\n\n\n\n<p style=\"text-align: justify;\">El pasado 30 de abril, en UNIAGRARIA demostramos que la sostenibilidad no es solo un discurso, sino una acci\u00f3n que se construye en comunidad. Durante nuestra Jornada de Reciclat\u00f3n, estudiantes, administrativos y colaboradores unieron esfuerzos para recolectar residuos y participar en una jornada llena de conciencia ambiental, compromiso social y aprendizajes transformadores.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Gracias al trabajo articulado entre el Departamento de Ingenier\u00eda Ambiental, el grupo COLEC y el equipo de Seguridad y Salud en el Trabajo, y con el respaldo del semillero Sostenibilidad Ambiental y Territorio, se lograron recolectar:<\/p>\n\n\n\n<ul style=\"text-align: justify;\"><li>10.8 kg de Recobotellas con pl\u00e1stico flexible de un solo uso<\/li><li>1.057 kg de RAEE (residuos de aparatos el\u00e9ctricos y electr\u00f3nicos)<\/li><li>21 kg de tapas pl\u00e1sticas<\/li><li>54.2 kg de ropa usada<\/li><\/ul>\n\n\n\n<p style=\"text-align: justify;\">Lo m\u00e1s importante: \u00a1todo este material tendr\u00e1 una segunda vida!<\/p>\n\n\n\n<p style=\"text-align: justify;\">Las Recobotellas y los RAEE ser\u00e1n transformados en nuevos productos gracias al trabajo conjunto con el grupo Recolec.<\/p>\n\n\n\n<p style=\"text-align: justify;\">La ropa usada ser\u00e1 convertida en \u00fatiles escolares a trav\u00e9s del emprendimiento Vuelta a Tela, liderado por Josep, estudiante de Ingenier\u00eda Ambiental.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Las tapitas pl\u00e1sticas ser\u00e1n gestionadas por la fundaci\u00f3n Tapitas x Patitas, que financia el cuidado de animales en condici\u00f3n de calle mediante el reciclaje.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Durante la jornada tambi\u00e9n se reconoci\u00f3 el esfuerzo de quienes se destacaron por su compromiso ambiental:<\/p>\n\n\n\n<ul style=\"text-align: justify;\"><li>El \u00e1rea de Log\u00edstica, que lider\u00f3 la recolecci\u00f3n de RAEE con m\u00e1s de 800 kg.<\/li><li>El programa de Ingenier\u00eda Ambiental, que recolect\u00f3 3.6 kg de Recobotellas.<\/li><\/ul>\n\n\n\n<p style=\"text-align: justify;\">Este tipo de iniciativas reafirman el compromiso de UNIAGRARIA con su Pol\u00edtica Ambiental Institucional y con la formaci\u00f3n integral de profesionales con conciencia cr\u00edtica, compromiso ambiental y capacidad de transformar su entorno.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Porque en UNIAGRARIA no solo hablamos de sostenibilidad\u2026 \u00a1la vivimos con acci\u00f3n, reflexi\u00f3n y comunidad!<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/05\/ReciclatonUniagraria2025-06-1024x617.jpeg\" alt=\"\" data-id=\"49746\" data-link=\"https:\/\/www.uniagraria.edu.co\/reciclatonuniagraria2025-06\/\" class=\"wp-image-49746\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/05\/ReciclatonUniagraria2025-05-1024x768.jpeg\" alt=\"\" data-id=\"49745\" data-link=\"https:\/\/www.uniagraria.edu.co\/reciclatonuniagraria2025-05\/\" class=\"wp-image-49745\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/05\/ReciclatonUniagraria2025-04-1024x768.jpeg\" alt=\"\" data-id=\"49744\" data-link=\"https:\/\/www.uniagraria.edu.co\/reciclatonuniagraria2025-04\/\" class=\"wp-image-49744\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/05\/ReciclatonUniagraria2025-03-1024x768.jpeg\" alt=\"\" data-id=\"49743\" data-link=\"https:\/\/www.uniagraria.edu.co\/reciclatonuniagraria2025-03\/\" class=\"wp-image-49743\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/05\/ReciclatonUniagraria2025-02-768x1024.jpeg\" alt=\"\" data-id=\"49742\" data-link=\"https:\/\/www.uniagraria.edu.co\/reciclatonuniagraria2025-02\/\" class=\"wp-image-49742\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/05\/ReciclatonUniagraria2025-01-768x1024.jpeg\" alt=\"\" data-id=\"49741\" data-link=\"https:\/\/www.uniagraria.edu.co\/reciclatonuniagraria2025-01\/\" class=\"wp-image-49741\"\/><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n de Comunicaciones UNIAGRARIA El pasado 30 de abril, en UNIAGRARIA demostramos que la sostenibilidad no es solo un discurso, sino una acci\u00f3n que se construye en comunidad. Durante nuestra Jornada de Reciclat\u00f3n, estudiantes, administrativos y colaboradores unieron esfuerzos para recolectar residuos y participar en una jornada llena de conciencia ambiental, compromiso social y aprendizajes [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":49746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[35],"tags":[],"class_list":["post-49747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta - UNIAGRARIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniagraria.edu.co\/es\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta - UNIAGRARIA\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n de Comunicaciones UNIAGRARIA El pasado 30 de abril, en UNIAGRARIA demostramos que la sostenibilidad no es solo un discurso, sino una acci\u00f3n que se construye en comunidad. Durante nuestra Jornada de Reciclat\u00f3n, estudiantes, administrativos y colaboradores unieron esfuerzos para recolectar residuos y participar en una jornada llena de conciencia ambiental, compromiso social y aprendizajes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniagraria.edu.co\/es\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIAGRARIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-02T22:58:48+00:00\" \/>\n<meta name=\"author\" content=\"Comunicaciones UNIAGRARIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:site\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones UNIAGRARIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/\"},\"author\":{\"name\":\"Comunicaciones UNIAGRARIA\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/f2ff0c07d9addb88b935755100b8db03\"},\"headline\":\"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta\",\"datePublished\":\"2025-05-02T22:58:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/\"},\"wordCount\":317,\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/\",\"name\":\"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta - UNIAGRARIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2025-05-02T22:58:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"name\":\"UNIAGRARIA\",\"description\":\"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\",\"name\":\"UNIAGRARIA\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"contentUrl\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"width\":3300,\"height\":2550,\"caption\":\"UNIAGRARIA\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uagraria\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/UNIAGRARIA\",\"https:\\\/\\\/www.instagram.com\\\/uniagraria\\\/profilecard\\\/?igsh=MXI2bTFlMWsxNzNjOA\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/uniagraria?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/uniagraria\\\/?originalSubdomain=co\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UniagrariaUverde?themeRefresh=1\",\"https:\\\/\\\/api.whatsapp.com\\\/send?phone=3134230649\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/f2ff0c07d9addb88b935755100b8db03\",\"name\":\"Comunicaciones UNIAGRARIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones UNIAGRARIA\"},\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/author\\\/4ndr3sf371p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta - UNIAGRARIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniagraria.edu.co\/es\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/","og_locale":"es_ES","og_type":"article","og_title":"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta - UNIAGRARIA","og_description":"Direcci\u00f3n de Comunicaciones UNIAGRARIA El pasado 30 de abril, en UNIAGRARIA demostramos que la sostenibilidad no es solo un discurso, sino una acci\u00f3n que se construye en comunidad. Durante nuestra Jornada de Reciclat\u00f3n, estudiantes, administrativos y colaboradores unieron esfuerzos para recolectar residuos y participar en una jornada llena de conciencia ambiental, compromiso social y aprendizajes [&hellip;]","og_url":"https:\/\/uniagraria.edu.co\/es\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/","og_site_name":"UNIAGRARIA","article_publisher":"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","article_published_time":"2025-05-02T22:58:48+00:00","author":"Comunicaciones UNIAGRARIA","twitter_card":"summary_large_image","twitter_creator":"@UNIAGRARIA","twitter_site":"@UNIAGRARIA","twitter_misc":{"Escrito por":"Comunicaciones UNIAGRARIA","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/#article","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/"},"author":{"name":"Comunicaciones UNIAGRARIA","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/f2ff0c07d9addb88b935755100b8db03"},"headline":"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta","datePublished":"2025-05-02T22:58:48+00:00","mainEntityOfPage":{"@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/"},"wordCount":317,"publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"image":{"@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/","url":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/","name":"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta - UNIAGRARIA","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/#primaryimage"},"image":{"@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/#primaryimage"},"thumbnailUrl":"","datePublished":"2025-05-02T22:58:48+00:00","breadcrumb":{"@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/uniagraria.edu.co\/en\/reciclaton-uniagraria-una-jornada-de-accion-colectiva-por-el-planeta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/uniagraria.edu.co\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/uniagraria.edu.co\/es\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Reciclat\u00f3n UNIAGRARIA: una jornada de acci\u00f3n colectiva por el planeta"}]},{"@type":"WebSite","@id":"https:\/\/uniagraria.edu.co\/es\/#website","url":"https:\/\/uniagraria.edu.co\/es\/","name":"UNIAGRARIA","description":"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA","publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniagraria.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/uniagraria.edu.co\/es\/#organization","name":"UNIAGRARIA","url":"https:\/\/uniagraria.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","contentUrl":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","width":3300,"height":2550,"caption":"UNIAGRARIA"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","https:\/\/x.com\/UNIAGRARIA","https:\/\/www.instagram.com\/uniagraria\/profilecard\/?igsh=MXI2bTFlMWsxNzNjOA","https:\/\/www.tiktok.com\/discover\/uniagraria?lang=es","https:\/\/www.linkedin.com\/school\/uniagraria\/?originalSubdomain=co","https:\/\/www.youtube.com\/user\/UniagrariaUverde?themeRefresh=1","https:\/\/api.whatsapp.com\/send?phone=3134230649"]},{"@type":"Person","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/f2ff0c07d9addb88b935755100b8db03","name":"Comunicaciones UNIAGRARIA","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","caption":"Comunicaciones UNIAGRARIA"},"url":"https:\/\/uniagraria.edu.co\/es\/author\/4ndr3sf371p3\/"}]}},"_links":{"self":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/49747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/comments?post=49747"}],"version-history":[{"count":0,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/49747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/media?parent=49747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/categories?post=49747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/tags?post=49747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}