{"id":69021,"date":"2025-03-28T08:45:13","date_gmt":"2025-03-28T13:45:13","guid":{"rendered":"https:\/\/www.uniagraria.edu.co\/?p=48198"},"modified":"2025-03-28T08:45:13","modified_gmt":"2025-03-28T13:45:13","slug":"uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac","status":"publish","type":"post","link":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/","title":{"rendered":"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres  de la L\u00ednea 4 de Fortalecimiento del SIAC"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\" id=\"mce_0\"><strong>Direcci\u00f3n de Comunicaciones UNIAGRARIA<\/strong><\/h4>\n\n\n\n<p style=\"text-align: justify;\">En el marco de la convocatoria para fortalecer los Sistemas Internos de Aseguramiento de la Calidad (SIAC) en las Instituciones de Educaci\u00f3n Superior (IES) de Colombia, UNIAGRARIA particip\u00f3 el d\u00eda de hoy, en la Socializaci\u00f3n de los Resultados de los talleres de la L\u00ednea 4 de fortalecimiento del SIAC, organizado por el Ministerio de Educaci\u00f3n Nacional y la Instituci\u00f3n Universitaria Pascual Bravo.<\/p>\n\n\n\n<p style=\"text-align: justify;\">Durante la jornada, el Ing. Benjam\u00edn Cepeda R., Director de Aseguramiento de la Calidad, y el Ing. Johan Esteban Villamil, Director del programa de Ingenier\u00eda de Alimentos, presentaron los indicadores para la medici\u00f3n de resultados, logros e impactos del proyecto &#8220;Generaci\u00f3n de valor agregado a la cadena hortofrut\u00edcola de Anolaima PE:180005&#8221;, desarrollado en colaboraci\u00f3n con la Asociaci\u00f3n de Productores de Aguacate de Anolaima.<\/p>\n\n\n\n<p style=\"text-align: justify;\">As\u00ed las cosas, de manera conjunta con el equipo de Aseguramiento de la Calidad, la Vicerrector\u00eda de Investigaciones, la Direcci\u00f3n de Planeaci\u00f3n y Prospectiva, y la Direcci\u00f3n del programa de Ingenier\u00eda de Alimentos de UNIAGRARIA, dise\u00f1aron los indicadores alineados con los objetivos institucionales y se estableci\u00f3 un proceso de recolecci\u00f3n de evidencias que permitir\u00e1 demostrar los resultados, logros e impactos del proyecto misional, fortaleciendo su evaluaci\u00f3n integral y demostrando nuestro enfoque por la Sustentabilidad Ambiental, la Cultura del Emprendimiento y el Desarrollo Rural con enfoque Territorial. <\/p>\n\n\n\n<p style=\"text-align: justify;\">Esta iniciativa reafirma el compromiso de UNIAGRARIA con la mejora continua de los procesos, en busca de la excelencia acad\u00e9mica y administrativa para garantizar la calidad educativa de los programas y por supuesto, de la Instituci\u00f3n, contribuyendo al desarrollo sostenible de la naci\u00f3n y la construcci\u00f3n de un tejido social promisorio para el pa\u00eds.<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/03\/TalleresDeLaLineaFortalecimientoDelSIAC-01-1024x577.jpeg\" alt=\"\" data-id=\"48194\" data-link=\"https:\/\/www.uniagraria.edu.co\/talleresdelalineafortalecimientodelsiac-01\/\" class=\"wp-image-48194\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/03\/TalleresDeLaLineaFortalecimientoDelSIAC-02-1024x576.jpeg\" alt=\"\" data-id=\"48195\" data-link=\"https:\/\/www.uniagraria.edu.co\/talleresdelalineafortalecimientodelsiac-02\/\" class=\"wp-image-48195\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/03\/TalleresDeLaLineaFortalecimientoDelSIAC-03-1024x640.jpeg\" alt=\"\" data-id=\"48196\" data-link=\"https:\/\/www.uniagraria.edu.co\/talleresdelalineafortalecimientodelsiac-03\/\" class=\"wp-image-48196\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/www.uniagraria.edu.co\/wp-content\/uploads\/2025\/03\/TalleresDeLaLineaFortalecimientoDelSIAC-04-1024x640.jpeg\" alt=\"\" data-id=\"48197\" data-link=\"https:\/\/www.uniagraria.edu.co\/talleresdelalineafortalecimientodelsiac-04\/\" class=\"wp-image-48197\"\/><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n de Comunicaciones UNIAGRARIA En el marco de la convocatoria para fortalecer los Sistemas Internos de Aseguramiento de la Calidad (SIAC) en las Instituciones de Educaci\u00f3n Superior (IES) de Colombia, UNIAGRARIA particip\u00f3 el d\u00eda de hoy, en la Socializaci\u00f3n de los Resultados de los talleres de la L\u00ednea 4 de fortalecimiento del SIAC, organizado por [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":48194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[35],"tags":[],"class_list":["post-69021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC - UNIAGRARIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC - UNIAGRARIA\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n de Comunicaciones UNIAGRARIA En el marco de la convocatoria para fortalecer los Sistemas Internos de Aseguramiento de la Calidad (SIAC) en las Instituciones de Educaci\u00f3n Superior (IES) de Colombia, UNIAGRARIA particip\u00f3 el d\u00eda de hoy, en la Socializaci\u00f3n de los Resultados de los talleres de la L\u00ednea 4 de fortalecimiento del SIAC, organizado por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIAGRARIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-28T13:45:13+00:00\" \/>\n<meta name=\"author\" content=\"Comunicaciones UNIAGRARIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:site\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones UNIAGRARIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/\"},\"author\":{\"name\":\"Comunicaciones UNIAGRARIA\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/f2ff0c07d9addb88b935755100b8db03\"},\"headline\":\"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC\",\"datePublished\":\"2025-03-28T13:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/\"},\"wordCount\":315,\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/\",\"name\":\"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC - UNIAGRARIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2025-03-28T13:45:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/en\\\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"name\":\"UNIAGRARIA\",\"description\":\"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\",\"name\":\"UNIAGRARIA\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"contentUrl\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"width\":3300,\"height\":2550,\"caption\":\"UNIAGRARIA\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uagraria\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/UNIAGRARIA\",\"https:\\\/\\\/www.instagram.com\\\/uniagraria\\\/profilecard\\\/?igsh=MXI2bTFlMWsxNzNjOA\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/uniagraria?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/uniagraria\\\/?originalSubdomain=co\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UniagrariaUverde?themeRefresh=1\",\"https:\\\/\\\/api.whatsapp.com\\\/send?phone=3134230649\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/f2ff0c07d9addb88b935755100b8db03\",\"name\":\"Comunicaciones UNIAGRARIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones UNIAGRARIA\"},\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/author\\\/4ndr3sf371p3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC - UNIAGRARIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/","og_locale":"es_ES","og_type":"article","og_title":"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC - UNIAGRARIA","og_description":"Direcci\u00f3n de Comunicaciones UNIAGRARIA En el marco de la convocatoria para fortalecer los Sistemas Internos de Aseguramiento de la Calidad (SIAC) en las Instituciones de Educaci\u00f3n Superior (IES) de Colombia, UNIAGRARIA particip\u00f3 el d\u00eda de hoy, en la Socializaci\u00f3n de los Resultados de los talleres de la L\u00ednea 4 de fortalecimiento del SIAC, organizado por [&hellip;]","og_url":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/","og_site_name":"UNIAGRARIA","article_publisher":"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","article_published_time":"2025-03-28T13:45:13+00:00","author":"Comunicaciones UNIAGRARIA","twitter_card":"summary_large_image","twitter_creator":"@UNIAGRARIA","twitter_site":"@UNIAGRARIA","twitter_misc":{"Escrito por":"Comunicaciones UNIAGRARIA","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/#article","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/"},"author":{"name":"Comunicaciones UNIAGRARIA","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/f2ff0c07d9addb88b935755100b8db03"},"headline":"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC","datePublished":"2025-03-28T13:45:13+00:00","mainEntityOfPage":{"@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/"},"wordCount":315,"publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"image":{"@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/","url":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/","name":"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC - UNIAGRARIA","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/#primaryimage"},"image":{"@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/#primaryimage"},"thumbnailUrl":"","datePublished":"2025-03-28T13:45:13+00:00","breadcrumb":{"@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/uniagraria.edu.co\/en\/uniagraria-participa-en-la-socializacion-de-los-resultados-de-los-talleres-de-la-linea-4-de-fortalecimiento-del-siac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/uniagraria.edu.co\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/uniagraria.edu.co\/es\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"UNIAGRARIA participa en la socializaci\u00f3n de los resultados de los Talleres de la L\u00ednea 4 de Fortalecimiento del SIAC"}]},{"@type":"WebSite","@id":"https:\/\/uniagraria.edu.co\/es\/#website","url":"https:\/\/uniagraria.edu.co\/es\/","name":"UNIAGRARIA","description":"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA","publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniagraria.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/uniagraria.edu.co\/es\/#organization","name":"UNIAGRARIA","url":"https:\/\/uniagraria.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","contentUrl":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","width":3300,"height":2550,"caption":"UNIAGRARIA"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","https:\/\/x.com\/UNIAGRARIA","https:\/\/www.instagram.com\/uniagraria\/profilecard\/?igsh=MXI2bTFlMWsxNzNjOA","https:\/\/www.tiktok.com\/discover\/uniagraria?lang=es","https:\/\/www.linkedin.com\/school\/uniagraria\/?originalSubdomain=co","https:\/\/www.youtube.com\/user\/UniagrariaUverde?themeRefresh=1","https:\/\/api.whatsapp.com\/send?phone=3134230649"]},{"@type":"Person","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/f2ff0c07d9addb88b935755100b8db03","name":"Comunicaciones UNIAGRARIA","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c34977f632fe7cabe2da5a1818394efca9475d46ad9f02e8eab7fd408884103?s=96&d=mm&r=g","caption":"Comunicaciones UNIAGRARIA"},"url":"https:\/\/uniagraria.edu.co\/es\/author\/4ndr3sf371p3\/"}]}},"_links":{"self":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/69021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/comments?post=69021"}],"version-history":[{"count":0,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/69021\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/media?parent=69021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/categories?post=69021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/tags?post=69021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}