{"id":76099,"date":"2025-07-21T08:30:23","date_gmt":"2025-07-21T13:30:23","guid":{"rendered":"https:\/\/novawebmaster.com\/uniagraria\/?p=76099"},"modified":"2025-07-21T08:30:23","modified_gmt":"2025-07-21T13:30:23","slug":"colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial","status":"publish","type":"post","link":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/","title":{"rendered":"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial"},"content":{"rendered":"<p>Lee el art\u00edculo de Boyac\u00e1 7 D\u00edas con la participaci\u00f3n de Carolina Z\u00fa\u00f1iga Fonseca, docente de la Facultad de Ciencias Jur\u00eddicas y Sociales de UNIAGRARIA.\u00a0<a href=\"https:\/\/boyaca7dias.com.co\/2025\/07\/18\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Lee el art\u00edculo de Boyac\u00e1 7 D\u00edas con la participaci\u00f3n de Carolina Z\u00fa\u00f1iga Fonseca, docente de la Facultad de Ciencias Jur\u00eddicas y Sociales de UNIAGRARIA. Nota completa. (abre en una nueva pesta\u00f1a)\"><strong>Nota completa.<\/strong><\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-76098 size-full\" src=\"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/07\/Boyaca7dias.png\" alt=\"\" width=\"1393\" height=\"873\" srcset=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias.png 1393w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias-300x188.png 300w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias-1024x642.png 1024w, https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias-768x481.png 768w\" sizes=\"(max-width: 1393px) 100vw, 1393px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lee el art\u00edculo de Boyac\u00e1 7 D\u00edas con la participaci\u00f3n de Carolina Z\u00fa\u00f1iga Fonseca, docente de la Facultad de Ciencias Jur\u00eddicas y Sociales de UNIAGRARIA.\u00a0Nota completa.<\/p>\n","protected":false},"author":5,"featured_media":76098,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[12],"tags":[],"class_list":["post-76099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-los-medios"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial - UNIAGRARIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial - UNIAGRARIA\" \/>\n<meta property=\"og:description\" content=\"Lee el art\u00edculo de Boyac\u00e1 7 D\u00edas con la participaci\u00f3n de Carolina Z\u00fa\u00f1iga Fonseca, docente de la Facultad de Ciencias Jur\u00eddicas y Sociales de UNIAGRARIA.\u00a0Nota completa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIAGRARIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-21T13:30:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1393\" \/>\n\t<meta property=\"og:image:height\" content=\"873\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comunicaciones UNIAGRARIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:site\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones UNIAGRARIA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/\"},\"author\":{\"name\":\"Comunicaciones UNIAGRARIA\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/0e33f5fa0e8c069958129cbe1ddd943f\"},\"headline\":\"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial\",\"datePublished\":\"2025-07-21T13:30:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/\"},\"wordCount\":53,\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Boyaca7dias.png\",\"articleSection\":[\"En los medios\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/\",\"name\":\"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial - UNIAGRARIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Boyaca7dias.png\",\"datePublished\":\"2025-07-21T13:30:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Boyaca7dias.png\",\"contentUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Boyaca7dias.png\",\"width\":1393,\"height\":873},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En los medios\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/category\\\/en-los-medios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"name\":\"UNIAGRARIA\",\"description\":\"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\",\"name\":\"UNIAGRARIA\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"contentUrl\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"width\":3300,\"height\":2550,\"caption\":\"UNIAGRARIA\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uagraria\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/UNIAGRARIA\",\"https:\\\/\\\/www.instagram.com\\\/uniagraria\\\/profilecard\\\/?igsh=MXI2bTFlMWsxNzNjOA\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/uniagraria?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/uniagraria\\\/?originalSubdomain=co\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UniagrariaUverde?themeRefresh=1\",\"https:\\\/\\\/api.whatsapp.com\\\/send?phone=3134230649\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/0e33f5fa0e8c069958129cbe1ddd943f\",\"name\":\"Comunicaciones UNIAGRARIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones UNIAGRARIA\"},\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/author\\\/daniel-castellanos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial - UNIAGRARIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/","og_locale":"es_ES","og_type":"article","og_title":"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial - UNIAGRARIA","og_description":"Lee el art\u00edculo de Boyac\u00e1 7 D\u00edas con la participaci\u00f3n de Carolina Z\u00fa\u00f1iga Fonseca, docente de la Facultad de Ciencias Jur\u00eddicas y Sociales de UNIAGRARIA.\u00a0Nota completa.","og_url":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/","og_site_name":"UNIAGRARIA","article_publisher":"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","article_published_time":"2025-07-21T13:30:23+00:00","og_image":[{"width":1393,"height":873,"url":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias.png","type":"image\/png"}],"author":"Comunicaciones UNIAGRARIA","twitter_card":"summary_large_image","twitter_creator":"@UNIAGRARIA","twitter_site":"@UNIAGRARIA","twitter_misc":{"Escrito por":"Comunicaciones UNIAGRARIA"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/#article","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/"},"author":{"name":"Comunicaciones UNIAGRARIA","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/0e33f5fa0e8c069958129cbe1ddd943f"},"headline":"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial","datePublished":"2025-07-21T13:30:23+00:00","mainEntityOfPage":{"@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/"},"wordCount":53,"publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/#primaryimage"},"thumbnailUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias.png","articleSection":["En los medios"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/","url":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/","name":"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial - UNIAGRARIA","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/#primaryimage"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/#primaryimage"},"thumbnailUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias.png","datePublished":"2025-07-21T13:30:23+00:00","breadcrumb":{"@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/#primaryimage","url":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias.png","contentUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/07\/Boyaca7dias.png","width":1393,"height":873},{"@type":"BreadcrumbList","@id":"https:\/\/uniagraria.edu.co\/es\/colombia-avanza-en-salud-mental-con-una-nueva-ley-que-prioriza-la-prevencion-la-atencion-integral-y-el-enfoque-territorial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/uniagraria.edu.co\/"},{"@type":"ListItem","position":2,"name":"En los medios","item":"https:\/\/uniagraria.edu.co\/es\/category\/en-los-medios\/"},{"@type":"ListItem","position":3,"name":"Colombia avanza en salud mental con una nueva ley que prioriza la prevenci\u00f3n, la atenci\u00f3n integral y el enfoque territorial"}]},{"@type":"WebSite","@id":"https:\/\/uniagraria.edu.co\/es\/#website","url":"https:\/\/uniagraria.edu.co\/es\/","name":"UNIAGRARIA","description":"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA","publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniagraria.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/uniagraria.edu.co\/es\/#organization","name":"UNIAGRARIA","url":"https:\/\/uniagraria.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","contentUrl":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","width":3300,"height":2550,"caption":"UNIAGRARIA"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","https:\/\/x.com\/UNIAGRARIA","https:\/\/www.instagram.com\/uniagraria\/profilecard\/?igsh=MXI2bTFlMWsxNzNjOA","https:\/\/www.tiktok.com\/discover\/uniagraria?lang=es","https:\/\/www.linkedin.com\/school\/uniagraria\/?originalSubdomain=co","https:\/\/www.youtube.com\/user\/UniagrariaUverde?themeRefresh=1","https:\/\/api.whatsapp.com\/send?phone=3134230649"]},{"@type":"Person","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/0e33f5fa0e8c069958129cbe1ddd943f","name":"Comunicaciones UNIAGRARIA","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","caption":"Comunicaciones UNIAGRARIA"},"url":"https:\/\/uniagraria.edu.co\/es\/author\/daniel-castellanos\/"}]}},"_links":{"self":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/76099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/comments?post=76099"}],"version-history":[{"count":0,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/76099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/media\/76098"}],"wp:attachment":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/media?parent=76099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/categories?post=76099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/tags?post=76099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}