{"id":77979,"date":"2025-10-07T15:53:22","date_gmt":"2025-10-07T20:53:22","guid":{"rendered":"http:\/\/192.168.30.11\/?p=77979"},"modified":"2025-10-07T15:54:06","modified_gmt":"2025-10-07T20:54:06","slug":"uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca","status":"publish","type":"post","link":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/","title":{"rendered":"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"77979\" class=\"elementor elementor-77979\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32dd8d7a e-flex e-con-boxed e-con e-parent\" data-id=\"32dd8d7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2261ba elementor-widget elementor-widget-text-editor\" data-id=\"f2261ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"uk-container uk-container-xsmall\">En coherencia con los pilares misionales de UNIAGRARIA y con el compromiso de aportar al desarrollo territorial a trav\u00e9s de la educaci\u00f3n, la Instituci\u00f3n particip\u00f3 a finales del mes pasado en la mesa de discusi\u00f3n de la Pol\u00edtica P\u00fablica de Educaci\u00f3n (PEM) en el municipio de La Mesa, Cundinamarca.<\/p>\r\n<p class=\"uk-container uk-container-xsmall\">La representaci\u00f3n estuvo a cargo del Director de las Dependencias de Facatativ\u00e1, Padre \u00c1ngel Alfaro, y del Director del Programa de Ingenier\u00eda Industrial, Andr\u00e9s Mauricio D\u00edaz, quienes hicieron parte activa de este espacio convocado por la administraci\u00f3n municipal con el prop\u00f3sito de construir bases s\u00f3lidas para fortalecer las alternativas educativas de la regi\u00f3n.<\/p>\r\n<p class=\"uk-container uk-container-xsmall\">Durante la jornada se destac\u00f3 la importancia de articular la educaci\u00f3n media con la educaci\u00f3n superior, a trav\u00e9s de acciones y pol\u00edticas p\u00fablicas concretas que permitan abrir nuevas oportunidades de formaci\u00f3n profesional para los j\u00f3venes del municipio y sus veredas.<\/p>\r\n<p class=\"uk-container uk-container-xsmall\">La participaci\u00f3n de UNIAGRARIA fue valorada como un aporte fundamental en la construcci\u00f3n del plan de desarrollo local, al convertirse en un actor protagonista de la transformaci\u00f3n educativa y social. Esta iniciativa responde a necesidades sentidas por padres de familia, estudiantes, profesores y rectores, quienes buscan garantizar a las nuevas generaciones un camino de continuidad acad\u00e9mica y la posibilidad de convertirse en impulsores del progreso regional.<\/p>\r\n<p class=\"uk-container uk-container-xsmall\">Este primer encuentro cont\u00f3 con el liderazgo de la Alcaldesa, Dra. Laura Londo\u00f1o Rodr\u00edguez, y del Secretario de Educaci\u00f3n, Daniel Alejandro G\u00f3mez Quintero, quienes resaltaron la relevancia del trabajo conjunto con la academia. Se espera que las conclusiones alcanzadas se consoliden en lo que resta del presente a\u00f1o, sentando un precedente para el futuro educativo de La Mesa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-217d128 e-flex e-con-boxed e-con e-parent\" data-id=\"217d128\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ca3063 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"3ca3063\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-0155b23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"MesaDeDiscusionSobrePol\u00edticaPublicaEnLaMesa\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En coherencia con los pilares misionales de UNIAGRARIA y con el compromiso de aportar al desarrollo territorial a trav\u00e9s de la educaci\u00f3n, la Instituci\u00f3n particip\u00f3 a finales del mes pasado en la mesa de discusi\u00f3n de la Pol\u00edtica P\u00fablica de Educaci\u00f3n (PEM) en el municipio de La Mesa, Cundinamarca. La representaci\u00f3n estuvo a cargo del [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":77978,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9,35],"tags":[],"class_list":["post-77979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca - UNIAGRARIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca - UNIAGRARIA\" \/>\n<meta property=\"og:description\" content=\"En coherencia con los pilares misionales de UNIAGRARIA y con el compromiso de aportar al desarrollo territorial a trav\u00e9s de la educaci\u00f3n, la Instituci\u00f3n particip\u00f3 a finales del mes pasado en la mesa de discusi\u00f3n de la Pol\u00edtica P\u00fablica de Educaci\u00f3n (PEM) en el municipio de La Mesa, Cundinamarca. La representaci\u00f3n estuvo a cargo del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIAGRARIA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T20:53:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T20:54:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/10\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaciones UNIAGRARIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:site\" content=\"@UNIAGRARIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaciones UNIAGRARIA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/\"},\"author\":{\"name\":\"Comunicaciones UNIAGRARIA\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/0e33f5fa0e8c069958129cbe1ddd943f\"},\"headline\":\"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca\",\"datePublished\":\"2025-10-07T20:53:22+00:00\",\"dateModified\":\"2025-10-07T20:54:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/\"},\"wordCount\":316,\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg\",\"articleSection\":[\"Noticia\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/\",\"name\":\"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca - UNIAGRARIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg\",\"datePublished\":\"2025-10-07T20:53:22+00:00\",\"dateModified\":\"2025-10-07T20:54:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg\",\"contentUrl\":\"https:\\\/\\\/uniagraria.edu.co\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia\",\"item\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/category\\\/noticia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"name\":\"UNIAGRARIA\",\"description\":\"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#organization\",\"name\":\"UNIAGRARIA\",\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"contentUrl\":\"https:\\\/\\\/novawebmaster.com\\\/uniagraria\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/LogoUa2023Vertical.png\",\"width\":3300,\"height\":2550,\"caption\":\"UNIAGRARIA\"},\"image\":{\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uagraria\\\/?locale=es_LA\",\"https:\\\/\\\/x.com\\\/UNIAGRARIA\",\"https:\\\/\\\/www.instagram.com\\\/uniagraria\\\/profilecard\\\/?igsh=MXI2bTFlMWsxNzNjOA\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/uniagraria?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/uniagraria\\\/?originalSubdomain=co\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/UniagrariaUverde?themeRefresh=1\",\"https:\\\/\\\/api.whatsapp.com\\\/send?phone=3134230649\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/#\\\/schema\\\/person\\\/0e33f5fa0e8c069958129cbe1ddd943f\",\"name\":\"Comunicaciones UNIAGRARIA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones UNIAGRARIA\"},\"url\":\"https:\\\/\\\/uniagraria.edu.co\\\/es\\\/author\\\/daniel-castellanos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca - UNIAGRARIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/","og_locale":"es_ES","og_type":"article","og_title":"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca - UNIAGRARIA","og_description":"En coherencia con los pilares misionales de UNIAGRARIA y con el compromiso de aportar al desarrollo territorial a trav\u00e9s de la educaci\u00f3n, la Instituci\u00f3n particip\u00f3 a finales del mes pasado en la mesa de discusi\u00f3n de la Pol\u00edtica P\u00fablica de Educaci\u00f3n (PEM) en el municipio de La Mesa, Cundinamarca. La representaci\u00f3n estuvo a cargo del [&hellip;]","og_url":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/","og_site_name":"UNIAGRARIA","article_publisher":"https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","article_published_time":"2025-10-07T20:53:22+00:00","article_modified_time":"2025-10-07T20:54:06+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/10\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg","type":"image\/jpeg"}],"author":"Comunicaciones UNIAGRARIA","twitter_card":"summary_large_image","twitter_creator":"@UNIAGRARIA","twitter_site":"@UNIAGRARIA","twitter_misc":{"Escrito por":"Comunicaciones UNIAGRARIA","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/#article","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/"},"author":{"name":"Comunicaciones UNIAGRARIA","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/0e33f5fa0e8c069958129cbe1ddd943f"},"headline":"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca","datePublished":"2025-10-07T20:53:22+00:00","dateModified":"2025-10-07T20:54:06+00:00","mainEntityOfPage":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/"},"wordCount":316,"publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/#primaryimage"},"thumbnailUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/10\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg","articleSection":["Noticia","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/","url":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/","name":"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca - UNIAGRARIA","isPartOf":{"@id":"https:\/\/uniagraria.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/#primaryimage"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/#primaryimage"},"thumbnailUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/10\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg","datePublished":"2025-10-07T20:53:22+00:00","dateModified":"2025-10-07T20:54:06+00:00","breadcrumb":{"@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/#primaryimage","url":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/10\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg","contentUrl":"https:\/\/uniagraria.edu.co\/wp-content\/uploads\/2025\/10\/MesaDeDiscusionSobrePoliticaPublicaEnLaMesa.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/uniagraria.edu.co\/es\/uniagraria-participa-en-mesa-de-discusion-sobre-politica-publica-de-educacion-en-la-mesa-cundinamarca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/uniagraria.edu.co\/"},{"@type":"ListItem","position":2,"name":"Noticia","item":"https:\/\/uniagraria.edu.co\/es\/category\/noticia\/"},{"@type":"ListItem","position":3,"name":"UNIAGRARIA participa en mesa de discusi\u00f3n sobre Pol\u00edtica P\u00fablica de Educaci\u00f3n en La Mesa, Cundinamarca"}]},{"@type":"WebSite","@id":"https:\/\/uniagraria.edu.co\/es\/#website","url":"https:\/\/uniagraria.edu.co\/es\/","name":"UNIAGRARIA","description":"FUNDACION UNIVERSITARIA AGRARIA DE COLOMBIA","publisher":{"@id":"https:\/\/uniagraria.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uniagraria.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/uniagraria.edu.co\/es\/#organization","name":"UNIAGRARIA","url":"https:\/\/uniagraria.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","contentUrl":"https:\/\/novawebmaster.com\/uniagraria\/wp-content\/uploads\/2025\/02\/LogoUa2023Vertical.png","width":3300,"height":2550,"caption":"UNIAGRARIA"},"image":{"@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uagraria\/?locale=es_LA","https:\/\/x.com\/UNIAGRARIA","https:\/\/www.instagram.com\/uniagraria\/profilecard\/?igsh=MXI2bTFlMWsxNzNjOA","https:\/\/www.tiktok.com\/discover\/uniagraria?lang=es","https:\/\/www.linkedin.com\/school\/uniagraria\/?originalSubdomain=co","https:\/\/www.youtube.com\/user\/UniagrariaUverde?themeRefresh=1","https:\/\/api.whatsapp.com\/send?phone=3134230649"]},{"@type":"Person","@id":"https:\/\/uniagraria.edu.co\/es\/#\/schema\/person\/0e33f5fa0e8c069958129cbe1ddd943f","name":"Comunicaciones UNIAGRARIA","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7e7249c4d3d9f8946f23544dbad58c5502cb22fc051cc2363fa7a13b9bc9939?s=96&d=mm&r=g","caption":"Comunicaciones UNIAGRARIA"},"url":"https:\/\/uniagraria.edu.co\/es\/author\/daniel-castellanos\/"}]}},"_links":{"self":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/77979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/comments?post=77979"}],"version-history":[{"count":0,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/posts\/77979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/media\/77978"}],"wp:attachment":[{"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/media?parent=77979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/categories?post=77979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uniagraria.edu.co\/es\/wp-json\/wp\/v2\/tags?post=77979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}